{"id":2163,"date":"2026-04-15T10:14:50","date_gmt":"2026-04-15T08:14:50","guid":{"rendered":"https:\/\/www.torellidottori.com\/?post_type=project&#038;p=2163"},"modified":"2026-05-07T09:07:13","modified_gmt":"2026-05-07T07:07:13","slug":"villa-bosdari","status":"publish","type":"project","link":"https:\/\/www.torellidottori.com\/it\/villa-bosdari\/","title":{"rendered":"Villa Bosdari"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-1a28912 stk-block-background\" data-block-id=\"1a28912\"><style>.stk-1a28912 {background-color:var(--theme-palette-color-8, #ffffff) !important;padding-top:120px !important;padding-right:0px !important;padding-bottom:220px !important;padding-left:0px !important;}.stk-1a28912:before{background-color:var(--theme-palette-color-8, #ffffff) !important;}.stk-1a28912-column{--stk-columns-spacing:0px !important;--stk-column-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}@media screen and (max-width:689px){.stk-1a28912 {padding-top:60px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-1a28912-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-7b461d9\" data-v=\"4\" data-block-id=\"7b461d9\"><style>@media screen and (min-width:690px){.stk-7b461d9 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-7b461d9-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-7b461d9-inner-blocks\">\n<p class=\"has-25-font-size\">La nostra impresa ha realizzato l\u2019intervento di restauro e risanamento conservativo dell\u2019ottocentesca Villa Bosdari di Ancona, situata all&#8217;interno del Parco Naturale del Conero in localit\u00e0 Trave e sottoposta a tutela dalla Sovrintendenza dei Beni Architettonici delle Marche. Il lavoro ha interessato le strutture, gli spazi interni ed esterni dell\u2019edificio e la sistemazione delle aree pertinenziali, nonch\u00e8 l\u2019annessa Chiesa e la casa colonica per un totale di n. 6 unit\u00e0 abitative.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ea3d3f5\" data-v=\"4\" data-block-id=\"ea3d3f5\"><style>.stk-ea3d3f5 {box-shadow:0px 12px 16px -6px #2339662e !important;border-style:solid !important;border-color:var(--theme-palette-color-1, #FE5200) !important;border-top-width:4px !important;border-right-width:0px !important;border-bottom-width:0px !important;border-left-width:0px !important;}@media screen and (min-width:690px){.stk-ea3d3f5 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}@media screen and (max-width:999px){.stk-ea3d3f5 {margin-top:60px !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ea3d3f5-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ea3d3f5-inner-blocks\">\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-aacc673\" data-block-id=\"aacc673\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-aacc673-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-77b4e76\" data-v=\"4\" data-block-id=\"77b4e76\"><style>.stk-77b4e76-container{margin-top:30px !important;margin-right:30px !important;margin-bottom:30px !important;margin-left:30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-77b4e76-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-77b4e76-inner-blocks\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-fe9cc265 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group w-100 is-layout-constrained wp-block-group-is-layout-constrained\" style=\"border-bottom-color:var(--wp--preset--color--palette-color-5);border-bottom-width:2px\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-bb407e5a wp-block-group-is-layout-flex\" style=\"padding-right:0;padding-bottom:var(--wp--preset--spacing--50);padding-left:0\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-574b6e3\" id=\"committente\" data-block-id=\"574b6e3\"><style>.stk-574b6e3 {margin-bottom:0px !important;}.stk-574b6e3 .stk-block-heading__text{text-transform:uppercase !important;}<\/style><h6 class=\"stk-block-heading__text\">Committente:<\/h6><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-6dc8795\" data-block-id=\"6dc8795\"><style>.stk-6dc8795 {margin-bottom:0px !important;}<\/style><p class=\"stk-block-text__text\">Torelli Beni Immobili Srl<\/p><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group w-100 is-layout-constrained wp-block-group-is-layout-constrained\" style=\"border-bottom-color:var(--wp--preset--color--palette-color-5);border-bottom-width:2px\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-bb407e5a wp-block-group-is-layout-flex\" style=\"padding-right:0;padding-bottom:var(--wp--preset--spacing--50);padding-left:0\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-43e8ac2\" id=\"regione\" data-block-id=\"43e8ac2\"><style>.stk-43e8ac2 {margin-bottom:0px !important;}.stk-43e8ac2 .stk-block-heading__text{text-transform:uppercase !important;}<\/style><h6 class=\"stk-block-heading__text\">Regione:<\/h6><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-ade8aa9\" data-block-id=\"ade8aa9\"><style>.stk-ade8aa9 {margin-bottom:0px !important;}<\/style><p class=\"stk-block-text__text\">Marche<\/p><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-1538eb62 wp-block-group-is-layout-flex\" style=\"padding-right:0;padding-left:0\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-69378c6\" id=\"localita\" data-block-id=\"69378c6\"><style>.stk-69378c6 {margin-bottom:0px !important;}.stk-69378c6 .stk-block-heading__text{text-transform:uppercase !important;}<\/style><h6 class=\"stk-block-heading__text\">Localit\u00e0:<\/h6><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-e9ddfb5\" data-block-id=\"e9ddfb5\"><style>.stk-e9ddfb5 {margin-bottom:0px !important;}<\/style><p class=\"stk-block-text__text\">Ancona loc. Trave<\/p><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-9d81a85\" data-block-id=\"9d81a85\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-9d81a85-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-0326574\" data-v=\"4\" data-block-id=\"0326574\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-0326574-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-0326574-inner-blocks\">\n<figure class=\"wp-block-image aligncenter size-full\" style=\"margin-top:-150px\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/1-3.webp\" alt=\"\" class=\"wp-image-2165\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/1-3.webp 2048w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/1-3-720x540.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/1-3-1920x1440.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/1-3-768x576.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/1-3-1536x1152.webp 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><figcaption class=\"wp-element-caption\">OLYMPUS DIGITAL CAMERA<\/figcaption><\/figure>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-91319a5 stk-block-background\" data-block-id=\"91319a5\"><style>.stk-91319a5 {background-color:var(--theme-palette-color-8, #ffffff) !important;padding-top:90px !important;padding-bottom:90px !important;}.stk-91319a5:before{background-color:var(--theme-palette-color-8, #ffffff) !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-91319a5-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c5c2d2a\" data-v=\"4\" data-block-id=\"c5c2d2a\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c5c2d2a-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c5c2d2a-inner-blocks\">\n<figure class=\"wp-block-gallery has-nested-images columns-5 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2-3.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1536\" data-id=\"2166\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2-3.webp\" alt=\"\" class=\"wp-image-2166\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2-3.webp 2048w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2-3-720x540.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2-3-1920x1440.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2-3-768x576.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2-3-1536x1152.webp 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/6-3.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1536\" data-id=\"2167\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/6-3.webp\" alt=\"\" class=\"wp-image-2167\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/6-3.webp 2048w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/6-3-720x540.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/6-3-1920x1440.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/6-3-768x576.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/6-3-1536x1152.webp 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/DSCN7689-scaled.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"2168\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/DSCN7689-scaled.webp\" alt=\"\" class=\"wp-image-2168\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/DSCN7689-scaled.webp 2560w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/DSCN7689-720x540.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/DSCN7689-1920x1440.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/DSCN7689-768x576.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/DSCN7689-1536x1152.webp 1536w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/DSCN7689-2048x1536.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0002.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1792\" height=\"1200\" data-id=\"2169\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0002.webp\" alt=\"\" class=\"wp-image-2169\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0002.webp 1792w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0002-720x482.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0002-768x514.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0002-1536x1029.webp 1536w\" sizes=\"auto, (max-width: 1792px) 100vw, 1792px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0011.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1792\" height=\"1200\" data-id=\"2170\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0011.webp\" alt=\"\" class=\"wp-image-2170\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0011.webp 1792w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0011-720x482.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0011-768x514.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0011-1536x1029.webp 1536w\" sizes=\"auto, (max-width: 1792px) 100vw, 1792px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0012.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1792\" height=\"1200\" data-id=\"2171\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0012.webp\" alt=\"\" class=\"wp-image-2171\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0012.webp 1792w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0012-720x482.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0012-768x514.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0012-1536x1029.webp 1536w\" sizes=\"auto, (max-width: 1792px) 100vw, 1792px\" \/><\/a><\/figure>\n<\/figure>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<p><\/p>\n","protected":false},"featured_media":2164,"menu_order":0,"template":"","meta":{"_acf_changed":true},"project-category":[14],"project-tag":[],"class_list":["post-2163","project","type-project","status-publish","has-post-thumbnail","hentry","project-category-sviluppo-immobiliare"],"blocksy_meta":[],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Villa Bosdari | Gruppo Torelli Dottori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.torellidottori.com\/it\/villa-bosdari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villa Bosdari | Gruppo Torelli Dottori\" \/>\n<meta property=\"og:description\" content=\"La nostra impresa ha realizzato l\u2019intervento di restauro e risanamento conservativo dell\u2019ottocentesca Villa Bosdari di Ancona, situata all&#8217;interno del Parco Naturale del Conero in localit\u00e0 Trave e sottoposta a tutela dalla Sovrintendenza dei Beni Architettonici delle Marche. Il lavoro ha interessato le strutture, gli spazi interni ed esterni dell\u2019edificio e la sistemazione delle aree pertinenziali, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.torellidottori.com\/it\/villa-bosdari\/\" \/>\n<meta property=\"og:site_name\" content=\"Gruppo Torelli Dottori\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T07:07:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0013.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1792\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/villa-bosdari\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/villa-bosdari\\\/\",\"name\":\"Villa Bosdari | Gruppo Torelli Dottori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/villa-bosdari\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/villa-bosdari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/PICT0013.webp\",\"datePublished\":\"2026-04-15T08:14:50+00:00\",\"dateModified\":\"2026-05-07T07:07:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/villa-bosdari\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/villa-bosdari\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/villa-bosdari\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/PICT0013.webp\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/PICT0013.webp\",\"width\":1792,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/villa-bosdari\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Villa Bosdari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\",\"name\":\"Gruppo Torelli Dottori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\",\"name\":\"Gruppo Torelli Dottori\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"width\":500,\"height\":214,\"caption\":\"Gruppo Torelli Dottori\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Villa Bosdari | Gruppo Torelli Dottori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.torellidottori.com\/it\/villa-bosdari\/","og_locale":"it_IT","og_type":"article","og_title":"Villa Bosdari | Gruppo Torelli Dottori","og_description":"La nostra impresa ha realizzato l\u2019intervento di restauro e risanamento conservativo dell\u2019ottocentesca Villa Bosdari di Ancona, situata all&#8217;interno del Parco Naturale del Conero in localit\u00e0 Trave e sottoposta a tutela dalla Sovrintendenza dei Beni Architettonici delle Marche. Il lavoro ha interessato le strutture, gli spazi interni ed esterni dell\u2019edificio e la sistemazione delle aree pertinenziali, [&hellip;]","og_url":"https:\/\/www.torellidottori.com\/it\/villa-bosdari\/","og_site_name":"Gruppo Torelli Dottori","article_modified_time":"2026-05-07T07:07:13+00:00","og_image":[{"width":1792,"height":1200,"url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0013.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.torellidottori.com\/it\/villa-bosdari\/","url":"https:\/\/www.torellidottori.com\/it\/villa-bosdari\/","name":"Villa Bosdari | Gruppo Torelli Dottori","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.torellidottori.com\/it\/villa-bosdari\/#primaryimage"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/villa-bosdari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0013.webp","datePublished":"2026-04-15T08:14:50+00:00","dateModified":"2026-05-07T07:07:13+00:00","breadcrumb":{"@id":"https:\/\/www.torellidottori.com\/it\/villa-bosdari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.torellidottori.com\/it\/villa-bosdari\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.torellidottori.com\/it\/villa-bosdari\/#primaryimage","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0013.webp","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/PICT0013.webp","width":1792,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.torellidottori.com\/it\/villa-bosdari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.torellidottori.com\/it\/"},{"@type":"ListItem","position":2,"name":"Villa Bosdari"}]},{"@type":"WebSite","@id":"https:\/\/www.torellidottori.com\/it\/#website","url":"https:\/\/www.torellidottori.com\/it\/","name":"Gruppo Torelli Dottori","description":"","publisher":{"@id":"https:\/\/www.torellidottori.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.torellidottori.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.torellidottori.com\/it\/#organization","name":"Gruppo Torelli Dottori","url":"https:\/\/www.torellidottori.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","width":500,"height":214,"caption":"Gruppo Torelli Dottori"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/logo\/image\/"}}]}},"mfb_rest_fields":["title","blocksy_meta","yoast_head","yoast_head_json"],"_links":{"self":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/project\/2163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/media\/2164"}],"wp:attachment":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/media?parent=2163"}],"wp:term":[{"taxonomy":"project-category","embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/project-category?post=2163"},{"taxonomy":"project-tag","embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/project-tag?post=2163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}