{"id":1544,"date":"2026-03-10T12:50:25","date_gmt":"2026-03-10T11:50:25","guid":{"rendered":"https:\/\/www.torellidottori.com\/?post_type=project&#038;p=1544"},"modified":"2026-04-15T10:21:13","modified_gmt":"2026-04-15T08:21:13","slug":"centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria","status":"publish","type":"project","link":"https:\/\/www.torellidottori.com\/it\/project\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\/","title":{"rendered":"Centro per la conservazione e valorizzazione dei beni storici, artistici e librari dell\u2019Umbria"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-1a28912 stk-block-background\" data-block-id=\"1a28912\"><style>.stk-1a28912 {background-color:var(--theme-palette-color-8, #ffffff) !important;padding-top:120px !important;padding-right:0px !important;padding-bottom:220px !important;padding-left:0px !important;}.stk-1a28912:before{background-color:var(--theme-palette-color-8, #ffffff) !important;}.stk-1a28912-column{--stk-columns-spacing:0px !important;--stk-column-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}@media screen and (max-width:689px){.stk-1a28912 {padding-top:60px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-1a28912-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-7b461d9\" data-v=\"4\" data-block-id=\"7b461d9\"><style>@media screen and (min-width:690px){.stk-7b461d9 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-7b461d9-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-7b461d9-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-0b0407f\" id=\"strong-realizzazione-centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dell-umbria-strong\" data-block-id=\"0b0407f\"><style>.stk-0b0407f .stk-block-heading__text{font-size:25px !important;}@media screen and (max-width:999px){.stk-0b0407f .stk-block-heading__text{font-size:25px !important;}}<\/style><h2 class=\"stk-block-heading__text\"><strong>Realizzazione centro per la conservazione e valorizzazione dei beni storici, artistici e librari dell\u2019Umbria<\/strong><\/h2><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-fe3f108\" data-block-id=\"fe3f108\"><p class=\"stk-block-text__text\">La struttura in cemento armato su isolatori \u00e8 stata realizzata in modo da disegnare le facciate inclinate. L\u2019aspetto molto semplice e lineare viene arricchito dalla presenza di una fascia di colore rosso che evidenzia la base e gli ingressi.<\/p><\/div>\n\n\n\n<p>Si tratta di un capannone polifunzionale destinato a centro operativo per la conservazione e la valorizzazione dei beni storico-artistici, archivistici e librari dell\u2019Umbria. Costruito a regola d\u2019arte secondo gli standard normativi e nel rispetto delle specifiche esigenze della destinazione d\u2019uso, \u00e8 stato inserito all\u2019interno delle \u201cLinee guida per l\u2019individuazione, l\u2019adeguamento, la progettazione e l\u2019allestimento di depositi per il ricovero temporaneo di beni culturali mobili con annessi laboratori di restauro\u201d del Ministero della Cultura come esempio di buona norma da seguire per la corretta progettazione e realizzazione di questa tipologia di strutture.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ea3d3f5\" data-v=\"4\" data-block-id=\"ea3d3f5\"><style>.stk-ea3d3f5 {box-shadow:0px 12px 16px -6px #2339662e !important;border-style:solid !important;border-color:var(--theme-palette-color-1, #FE5200) !important;border-top-width:4px !important;border-right-width:0px !important;border-bottom-width:0px !important;border-left-width:0px !important;}@media screen and (min-width:690px){.stk-ea3d3f5 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}@media screen and (max-width:999px){.stk-ea3d3f5 {margin-top:60px !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ea3d3f5-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ea3d3f5-inner-blocks\">\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-aacc673\" data-block-id=\"aacc673\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-aacc673-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-77b4e76\" data-v=\"4\" data-block-id=\"77b4e76\"><style>.stk-77b4e76-container{margin-top:30px !important;margin-right:30px !important;margin-bottom:30px !important;margin-left:30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-77b4e76-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-77b4e76-inner-blocks\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-fe9cc265 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group w-100 is-layout-constrained wp-block-group-is-layout-constrained\" style=\"border-bottom-color:var(--wp--preset--color--palette-color-5);border-bottom-width:2px\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-bb407e5a wp-block-group-is-layout-flex\" style=\"padding-right:0;padding-bottom:var(--wp--preset--spacing--50);padding-left:0\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-574b6e3\" id=\"committente\" data-block-id=\"574b6e3\"><style>.stk-574b6e3 {margin-bottom:0px !important;}.stk-574b6e3 .stk-block-heading__text{text-transform:uppercase !important;}<\/style><h6 class=\"stk-block-heading__text\">Committente:<\/h6><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-6dc8795\" data-block-id=\"6dc8795\"><style>.stk-6dc8795 {margin-bottom:0px !important;}<\/style><p class=\"stk-block-text__text\">Comune di Spoleto<\/p><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group w-100 is-layout-constrained wp-block-group-is-layout-constrained\" style=\"border-bottom-color:var(--wp--preset--color--palette-color-5);border-bottom-width:2px\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-bb407e5a wp-block-group-is-layout-flex\" style=\"padding-right:0;padding-bottom:var(--wp--preset--spacing--50);padding-left:0\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-43e8ac2\" id=\"regione\" data-block-id=\"43e8ac2\"><style>.stk-43e8ac2 {margin-bottom:0px !important;}.stk-43e8ac2 .stk-block-heading__text{text-transform:uppercase !important;}<\/style><h6 class=\"stk-block-heading__text\">Regione:<\/h6><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-ade8aa9\" data-block-id=\"ade8aa9\"><style>.stk-ade8aa9 {margin-bottom:0px !important;}<\/style><p class=\"stk-block-text__text\">Umbria<\/p><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-1538eb62 wp-block-group-is-layout-flex\" style=\"padding-right:0;padding-left:0\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-69378c6\" id=\"localita\" data-block-id=\"69378c6\"><style>.stk-69378c6 {margin-bottom:0px !important;}.stk-69378c6 .stk-block-heading__text{text-transform:uppercase !important;}<\/style><h6 class=\"stk-block-heading__text\">Localit\u00e0:<\/h6><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-e9ddfb5\" data-block-id=\"e9ddfb5\"><style>.stk-e9ddfb5 {margin-bottom:0px !important;}<\/style><p class=\"stk-block-text__text\">Santo Chiodo &#8211; Comune di Spoleto (PG)<\/p><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-9d81a85\" data-block-id=\"9d81a85\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-9d81a85-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-0326574\" data-v=\"4\" data-block-id=\"0326574\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-0326574-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-0326574-inner-blocks\">\n<figure class=\"wp-block-image size-full\" style=\"margin-top:-150px\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/12062009320.webp\" alt=\"\" class=\"wp-image-1547\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/12062009320.webp 1600w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/12062009320-720x540.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/12062009320-768x576.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/12062009320-1536x1152.webp 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-91319a5 stk-block-background\" data-block-id=\"91319a5\"><style>.stk-91319a5 {background-color:var(--theme-palette-color-8, #ffffff) !important;padding-top:90px !important;padding-bottom:90px !important;}.stk-91319a5:before{background-color:var(--theme-palette-color-8, #ffffff) !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-91319a5-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c5c2d2a\" data-v=\"4\" data-block-id=\"c5c2d2a\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c5c2d2a-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c5c2d2a-inner-blocks\">\n<figure class=\"wp-block-gallery has-nested-images columns-5 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/12062009318.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" data-id=\"1548\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/12062009318.webp\" alt=\"\" class=\"wp-image-1548\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/12062009318.webp 1600w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/12062009318-720x540.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/12062009318-768x576.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/12062009318-1536x1152.webp 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/01042008104.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" data-id=\"1549\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/01042008104.webp\" alt=\"\" class=\"wp-image-1549\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/01042008104.webp 1600w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/01042008104-720x540.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/01042008104-768x576.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/01042008104-1536x1152.webp 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/3939955_orig.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"618\" data-id=\"1550\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/3939955_orig.webp\" alt=\"\" class=\"wp-image-1550\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/3939955_orig.webp 1100w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/3939955_orig-720x405.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/3939955_orig-768x431.webp 768w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/307443_orig.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"618\" data-id=\"1551\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/307443_orig.webp\" alt=\"\" class=\"wp-image-1551\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/307443_orig.webp 1100w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/307443_orig-720x405.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/307443_orig-768x431.webp 768w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/7.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"618\" data-id=\"1552\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/7.webp\" alt=\"\" class=\"wp-image-1552\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/7.webp 1100w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/7-720x405.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/7-768x431.webp 768w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/a><\/figure>\n<\/figure>\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"featured_media":1546,"menu_order":0,"template":"","meta":{"_acf_changed":true},"project-category":[11],"project-tag":[],"class_list":["post-1544","project","type-project","status-publish","has-post-thumbnail","hentry","project-category-edilizia"],"blocksy_meta":[],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centro per la conservazione e valorizzazione dei beni storici, artistici e librari dell\u2019Umbria | Gruppo Torelli Dottori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.torellidottori.com\/it\/project\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centro per la conservazione e valorizzazione dei beni storici, artistici e librari dell\u2019Umbria | Gruppo Torelli Dottori\" \/>\n<meta property=\"og:description\" content=\"Realizzazione centro per la conservazione e valorizzazione dei beni storici, artistici e librari dell\u2019Umbria La struttura in cemento armato su isolatori \u00e8 stata realizzata in modo da disegnare le facciate inclinate. L\u2019aspetto molto semplice e lineare viene arricchito dalla presenza di una fascia di colore rosso che evidenzia la base e gli ingressi. Si tratta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.torellidottori.com\/it\/project\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\/\" \/>\n<meta property=\"og:site_name\" content=\"Gruppo Torelli Dottori\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T08:21:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/P1020422.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/project\\\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/project\\\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\\\/\",\"name\":\"Centro per la conservazione e valorizzazione dei beni storici, artistici e librari dell\u2019Umbria | Gruppo Torelli Dottori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/project\\\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/project\\\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/P1020422.webp\",\"datePublished\":\"2026-03-10T11:50:25+00:00\",\"dateModified\":\"2026-04-15T08:21:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/project\\\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/project\\\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/project\\\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/P1020422.webp\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/P1020422.webp\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/project\\\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centro per la conservazione e valorizzazione dei beni storici, artistici e librari dell\u2019Umbria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\",\"name\":\"Gruppo Torelli Dottori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\",\"name\":\"Gruppo Torelli Dottori\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"width\":500,\"height\":214,\"caption\":\"Gruppo Torelli Dottori\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centro per la conservazione e valorizzazione dei beni storici, artistici e librari dell\u2019Umbria | Gruppo Torelli Dottori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.torellidottori.com\/it\/project\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\/","og_locale":"it_IT","og_type":"article","og_title":"Centro per la conservazione e valorizzazione dei beni storici, artistici e librari dell\u2019Umbria | Gruppo Torelli Dottori","og_description":"Realizzazione centro per la conservazione e valorizzazione dei beni storici, artistici e librari dell\u2019Umbria La struttura in cemento armato su isolatori \u00e8 stata realizzata in modo da disegnare le facciate inclinate. L\u2019aspetto molto semplice e lineare viene arricchito dalla presenza di una fascia di colore rosso che evidenzia la base e gli ingressi. Si tratta [&hellip;]","og_url":"https:\/\/www.torellidottori.com\/it\/project\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\/","og_site_name":"Gruppo Torelli Dottori","article_modified_time":"2026-04-15T08:21:13+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/P1020422.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.torellidottori.com\/it\/project\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\/","url":"https:\/\/www.torellidottori.com\/it\/project\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\/","name":"Centro per la conservazione e valorizzazione dei beni storici, artistici e librari dell\u2019Umbria | Gruppo Torelli Dottori","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.torellidottori.com\/it\/project\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\/#primaryimage"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/project\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/P1020422.webp","datePublished":"2026-03-10T11:50:25+00:00","dateModified":"2026-04-15T08:21:13+00:00","breadcrumb":{"@id":"https:\/\/www.torellidottori.com\/it\/project\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.torellidottori.com\/it\/project\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.torellidottori.com\/it\/project\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\/#primaryimage","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/P1020422.webp","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/P1020422.webp","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/www.torellidottori.com\/it\/project\/centro-per-la-conservazione-e-valorizzazione-dei-beni-storici-artistici-e-librari-dellumbria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.torellidottori.com\/it\/"},{"@type":"ListItem","position":2,"name":"Centro per la conservazione e valorizzazione dei beni storici, artistici e librari dell\u2019Umbria"}]},{"@type":"WebSite","@id":"https:\/\/www.torellidottori.com\/it\/#website","url":"https:\/\/www.torellidottori.com\/it\/","name":"Gruppo Torelli Dottori","description":"","publisher":{"@id":"https:\/\/www.torellidottori.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.torellidottori.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.torellidottori.com\/it\/#organization","name":"Gruppo Torelli Dottori","url":"https:\/\/www.torellidottori.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","width":500,"height":214,"caption":"Gruppo Torelli Dottori"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/logo\/image\/"}}]}},"mfb_rest_fields":["title","blocksy_meta","yoast_head","yoast_head_json"],"_links":{"self":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/project\/1544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/media\/1546"}],"wp:attachment":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/media?parent=1544"}],"wp:term":[{"taxonomy":"project-category","embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/project-category?post=1544"},{"taxonomy":"project-tag","embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/project-tag?post=1544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}