{"id":13,"count":8,"description":"La nostra impresa realizza opere infrastrutturali nell\u2019ambito di lavori stradali, opere idrauliche e interventi urbanistici gestendo ogni fase esecutiva con personale specializzato e mezzi propri. L\u2019esperienza maturata sul campo ci permette di affrontare lavorazioni complesse, coordinare pi\u00f9 attivit\u00e0 simultanee e adattarci alle condizioni del territorio, mantenendo sempre elevata la qualit\u00e0 delle opere realizzate.","link":"https:\/\/www.torellidottori.com\/it\/appalti\/infrastrutture\/","name":"Infrastrutture","slug":"infrastrutture","taxonomy":"project-category","parent":10,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Infrastrutture | Gruppo Torelli Dottori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.torellidottori.com\/it\/appalti\/infrastrutture\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Infrastrutture | Gruppo Torelli Dottori\" \/>\n<meta property=\"og:description\" content=\"La nostra impresa realizza opere infrastrutturali nell\u2019ambito di lavori stradali, opere idrauliche e interventi urbanistici gestendo ogni fase esecutiva con personale specializzato e mezzi propri. L\u2019esperienza maturata sul campo ci permette di affrontare lavorazioni complesse, coordinare pi\u00f9 attivit\u00e0 simultanee e adattarci alle condizioni del territorio, mantenendo sempre elevata la qualit\u00e0 delle opere realizzate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.torellidottori.com\/it\/appalti\/infrastrutture\/\" \/>\n<meta property=\"og:site_name\" content=\"Gruppo Torelli Dottori\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/01\/IMG_5561_bw.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/appalti\\\/infrastrutture\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/appalti\\\/infrastrutture\\\/\",\"name\":\"Infrastrutture | Gruppo Torelli Dottori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/appalti\\\/infrastrutture\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/appalti\\\/infrastrutture\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Appalti\",\"item\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/appalti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Infrastrutture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\",\"name\":\"Gruppo Torelli Dottori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\",\"name\":\"Gruppo Torelli Dottori\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"width\":500,\"height\":214,\"caption\":\"Gruppo Torelli Dottori\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Infrastrutture | Gruppo Torelli Dottori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.torellidottori.com\/it\/appalti\/infrastrutture\/","og_locale":"it_IT","og_type":"article","og_title":"Infrastrutture | Gruppo Torelli Dottori","og_description":"La nostra impresa realizza opere infrastrutturali nell\u2019ambito di lavori stradali, opere idrauliche e interventi urbanistici gestendo ogni fase esecutiva con personale specializzato e mezzi propri. L\u2019esperienza maturata sul campo ci permette di affrontare lavorazioni complesse, coordinare pi\u00f9 attivit\u00e0 simultanee e adattarci alle condizioni del territorio, mantenendo sempre elevata la qualit\u00e0 delle opere realizzate.","og_url":"https:\/\/www.torellidottori.com\/it\/appalti\/infrastrutture\/","og_site_name":"Gruppo Torelli Dottori","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/01\/IMG_5561_bw.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.torellidottori.com\/it\/appalti\/infrastrutture\/","url":"https:\/\/www.torellidottori.com\/it\/appalti\/infrastrutture\/","name":"Infrastrutture | Gruppo Torelli Dottori","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/www.torellidottori.com\/it\/appalti\/infrastrutture\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.torellidottori.com\/it\/appalti\/infrastrutture\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.torellidottori.com\/it\/"},{"@type":"ListItem","position":2,"name":"Appalti","item":"https:\/\/www.torellidottori.com\/it\/appalti\/"},{"@type":"ListItem","position":3,"name":"Infrastrutture"}]},{"@type":"WebSite","@id":"https:\/\/www.torellidottori.com\/it\/#website","url":"https:\/\/www.torellidottori.com\/it\/","name":"Gruppo Torelli Dottori","description":"","publisher":{"@id":"https:\/\/www.torellidottori.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.torellidottori.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.torellidottori.com\/it\/#organization","name":"Gruppo Torelli Dottori","url":"https:\/\/www.torellidottori.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","width":500,"height":214,"caption":"Gruppo Torelli Dottori"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/project-category\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/project-category"}],"about":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/taxonomies\/project-category"}],"up":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/project-category\/10"}],"wp:post_type":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/project?project-category=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}