{"id":1872,"date":"2015-12-07T15:50:56","date_gmt":"2015-12-07T14:50:56","guid":{"rendered":"https:\/\/www.torellidottori.com\/?p=1872"},"modified":"2026-05-08T11:15:12","modified_gmt":"2026-05-08T09:15:12","slug":"cascina-triulza-expo","status":"publish","type":"post","link":"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/","title":{"rendered":"Cascina Triulza EXPO"},"content":{"rendered":"\n<p>Il complesso della Cascina Triulza, oggetto del presente progetto, \u00e8 ubicato in via Cristina di Belgioioso 171, all\u2019interno del Sito Espositivo di Expo 2015.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2015.12_Cascina-Triulza-EXPO.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incorporamento di 2015.12_Cascina Triulza EXPO.\"><\/object><a class=\"wp-element-button\" id=\"wp-block-file--media-645862f9-7eed-4dbb-aa0f-46b5b93b7961\" href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2015.12_Cascina-Triulza-EXPO.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Visualizza<\/a><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2015.12_Cascina-Triulza-EXPO.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-645862f9-7eed-4dbb-aa0f-46b5b93b7961\">Scarica l&#8217;articolo<\/a><\/div>\n\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider stk-block stk-b8e5656\" data-block-id=\"b8e5656\"><style>.stk-b8e5656 hr.stk-block-divider__hr{background:var(--theme-palette-color-5, #e1e8ed) !important;height:2px !important;width:100% !important;}.stk-b8e5656 {padding-top:var(--stk--preset--spacing--60, 2.25rem) !important;padding-bottom:var(--stk--preset--spacing--60, 2.25rem) !important;}<\/style><hr class=\"stk-block-divider__hr\"\/><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-ec8efb1\" id=\"scopri-il-progetto-realizzato\" data-block-id=\"ec8efb1\"><h4 class=\"stk-block-heading__text\">Scopri il progetto realizzato<\/h4><\/div>\n\n\n\n<div class=\"wp-block-query is-layout-flow wp-block-query-is-layout-flow\"><ul class=\"wp-block-post-template is-layout-flow wp-block-post-template-is-layout-flow\"><li class=\"wp-block-post post-1190 project type-project status-publish has-post-thumbnail hentry project-category-restauri\">\n\n<div class=\"wp-block-columns are-vertically-aligned-center has-palette-color-8-background-color has-background is-layout-flex wp-container-core-columns-is-layout-85958d59 wp-block-columns-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--40);padding-right:var(--wp--preset--spacing--40);padding-bottom:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--40)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.torellidottori.com\/it\/project\/riqualificazione-cascina-triulza-milano-expo-2015\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/TD_EXPO_IOA5821_TEMP.webp\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Riqualificazione Cascina Triulza \u2013 Milano Expo 2015\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/TD_EXPO_IOA5821_TEMP.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/TD_EXPO_IOA5821_TEMP-720x480.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/TD_EXPO_IOA5821_TEMP-768x512.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/TD_EXPO_IOA5821_TEMP-1536x1024.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\"><h4 class=\"wp-block-post-title\"><a href=\"https:\/\/www.torellidottori.com\/it\/project\/riqualificazione-cascina-triulza-milano-expo-2015\/\" target=\"_self\" >Riqualificazione Cascina Triulza \u2013 Milano Expo 2015<\/a><\/h4><\/div>\n<\/div>\n\n<\/li><\/ul><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il complesso della Cascina Triulza, oggetto del presente progetto, \u00e8 ubicato in via Cristina di Belgioioso 171, all\u2019interno del Sito Espositivo di Expo 2015. Scopri il progetto realizzato<\/p>\n","protected":false},"author":1,"featured_media":1874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-1872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"blocksy_meta":[],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cascina Triulza EXPO | Gruppo Torelli Dottori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cascina Triulza EXPO | Gruppo Torelli Dottori\" \/>\n<meta property=\"og:description\" content=\"Il complesso della Cascina Triulza, oggetto del presente progetto, \u00e8 ubicato in via Cristina di Belgioioso 171, all\u2019interno del Sito Espositivo di Expo 2015. Scopri il progetto realizzato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/\" \/>\n<meta property=\"og:site_name\" content=\"Gruppo Torelli Dottori\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-07T14:50:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T09:15:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-155041.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"873\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin_fliplab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_fliplab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/cascina-triulza-expo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/cascina-triulza-expo\\\/\"},\"author\":{\"name\":\"admin_fliplab\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/person\\\/2f1f4289eb9b223ef8a647f8ebd6ebb4\"},\"headline\":\"Cascina Triulza EXPO\",\"datePublished\":\"2015-12-07T14:50:56+00:00\",\"dateModified\":\"2026-05-08T09:15:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/cascina-triulza-expo\\\/\"},\"wordCount\":35,\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/cascina-triulza-expo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-155041.webp\",\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/cascina-triulza-expo\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/cascina-triulza-expo\\\/\",\"name\":\"Cascina Triulza EXPO | Gruppo Torelli Dottori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/cascina-triulza-expo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/cascina-triulza-expo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-155041.webp\",\"datePublished\":\"2015-12-07T14:50:56+00:00\",\"dateModified\":\"2026-05-08T09:15:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/cascina-triulza-expo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/cascina-triulza-expo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/cascina-triulza-expo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-155041.webp\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-155041.webp\",\"width\":873,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/cascina-triulza-expo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cascina Triulza EXPO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\",\"name\":\"Gruppo Torelli Dottori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\",\"name\":\"Gruppo Torelli Dottori\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"width\":500,\"height\":214,\"caption\":\"Gruppo Torelli Dottori\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/person\\\/2f1f4289eb9b223ef8a647f8ebd6ebb4\",\"name\":\"admin_fliplab\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g\",\"caption\":\"admin_fliplab\"},\"sameAs\":[\"https:\\\/\\\/www.torellidottori.com\"],\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/author\\\/admin_fliplab\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cascina Triulza EXPO | Gruppo Torelli Dottori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/","og_locale":"it_IT","og_type":"article","og_title":"Cascina Triulza EXPO | Gruppo Torelli Dottori","og_description":"Il complesso della Cascina Triulza, oggetto del presente progetto, \u00e8 ubicato in via Cristina di Belgioioso 171, all\u2019interno del Sito Espositivo di Expo 2015. Scopri il progetto realizzato","og_url":"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/","og_site_name":"Gruppo Torelli Dottori","article_published_time":"2015-12-07T14:50:56+00:00","article_modified_time":"2026-05-08T09:15:12+00:00","og_image":[{"width":873,"height":512,"url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-155041.webp","type":"image\/png"}],"author":"admin_fliplab","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin_fliplab","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/#article","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/"},"author":{"name":"admin_fliplab","@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/person\/2f1f4289eb9b223ef8a647f8ebd6ebb4"},"headline":"Cascina Triulza EXPO","datePublished":"2015-12-07T14:50:56+00:00","dateModified":"2026-05-08T09:15:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/"},"wordCount":35,"publisher":{"@id":"https:\/\/www.torellidottori.com\/it\/#organization"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-155041.webp","inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/","url":"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/","name":"Cascina Triulza EXPO | Gruppo Torelli Dottori","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/#primaryimage"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-155041.webp","datePublished":"2015-12-07T14:50:56+00:00","dateModified":"2026-05-08T09:15:12+00:00","breadcrumb":{"@id":"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/#primaryimage","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-155041.webp","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-155041.webp","width":873,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.torellidottori.com\/it\/cascina-triulza-expo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.torellidottori.com\/it\/"},{"@type":"ListItem","position":2,"name":"Cascina Triulza EXPO"}]},{"@type":"WebSite","@id":"https:\/\/www.torellidottori.com\/it\/#website","url":"https:\/\/www.torellidottori.com\/it\/","name":"Gruppo Torelli Dottori","description":"","publisher":{"@id":"https:\/\/www.torellidottori.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.torellidottori.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.torellidottori.com\/it\/#organization","name":"Gruppo Torelli Dottori","url":"https:\/\/www.torellidottori.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","width":500,"height":214,"caption":"Gruppo Torelli Dottori"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/person\/2f1f4289eb9b223ef8a647f8ebd6ebb4","name":"admin_fliplab","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g","caption":"admin_fliplab"},"sameAs":["https:\/\/www.torellidottori.com"],"url":"https:\/\/www.torellidottori.com\/it\/author\/admin_fliplab\/"}]}},"mfb_rest_fields":["title","blocksy_meta","yoast_head","yoast_head_json"],"_links":{"self":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/posts\/1872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/comments?post=1872"}],"version-history":[{"count":0,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/posts\/1872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/media\/1874"}],"wp:attachment":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/media?parent=1872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/categories?post=1872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/tags?post=1872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}