{"id":1860,"date":"2022-04-07T15:37:44","date_gmt":"2022-04-07T13:37:44","guid":{"rendered":"https:\/\/www.torellidottori.com\/?p=1860"},"modified":"2026-05-08T11:15:11","modified_gmt":"2026-05-08T09:15:11","slug":"costruzioni-antisismiche-torelli-dottori","status":"publish","type":"post","link":"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/","title":{"rendered":"Costruzioni antisismiche Torelli Dottori"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2022_Costruzioni-antisismiche-Torelli-Dottori.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incorporamento di 2022_Costruzioni antisismiche Torelli Dottori.\"><\/object><a class=\"wp-element-button\" id=\"wp-block-file--media-693cc973-6906-474e-ae04-72bc47645bc6\" href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2022_Costruzioni-antisismiche-Torelli-Dottori.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Visualizza<\/a><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2022_Costruzioni-antisismiche-Torelli-Dottori.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-693cc973-6906-474e-ae04-72bc47645bc6\">Scarica l&#8217;articolo<\/a><\/div>\n\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider stk-block stk-b8e5656\" data-block-id=\"b8e5656\"><style>.stk-b8e5656 hr.stk-block-divider__hr{background:var(--theme-palette-color-5, #e1e8ed) !important;height:2px !important;width:100% !important;}.stk-b8e5656 {padding-top:var(--stk--preset--spacing--60, 2.25rem) !important;padding-bottom:var(--stk--preset--spacing--60, 2.25rem) !important;}<\/style><hr class=\"stk-block-divider__hr\"\/><\/div>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1862,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-1860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"blocksy_meta":[],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Costruzioni antisismiche Torelli Dottori | Gruppo Torelli Dottori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Costruzioni antisismiche Torelli Dottori | Gruppo Torelli Dottori\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/\" \/>\n<meta property=\"og:site_name\" content=\"Gruppo Torelli Dottori\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-07T13:37:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T09:15:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-153729.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"433\" \/>\n\t<meta property=\"og:image:height\" content=\"273\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin_fliplab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_fliplab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/costruzioni-antisismiche-torelli-dottori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/costruzioni-antisismiche-torelli-dottori\\\/\"},\"author\":{\"name\":\"admin_fliplab\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/person\\\/2f1f4289eb9b223ef8a647f8ebd6ebb4\"},\"headline\":\"Costruzioni antisismiche Torelli Dottori\",\"datePublished\":\"2022-04-07T13:37:44+00:00\",\"dateModified\":\"2026-05-08T09:15:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/costruzioni-antisismiche-torelli-dottori\\\/\"},\"wordCount\":15,\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/costruzioni-antisismiche-torelli-dottori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-153729.webp\",\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/costruzioni-antisismiche-torelli-dottori\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/costruzioni-antisismiche-torelli-dottori\\\/\",\"name\":\"Costruzioni antisismiche Torelli Dottori | Gruppo Torelli Dottori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/costruzioni-antisismiche-torelli-dottori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/costruzioni-antisismiche-torelli-dottori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-153729.webp\",\"datePublished\":\"2022-04-07T13:37:44+00:00\",\"dateModified\":\"2026-05-08T09:15:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/costruzioni-antisismiche-torelli-dottori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/costruzioni-antisismiche-torelli-dottori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/costruzioni-antisismiche-torelli-dottori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-153729.webp\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-153729.webp\",\"width\":433,\"height\":273},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/costruzioni-antisismiche-torelli-dottori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Costruzioni antisismiche Torelli Dottori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\",\"name\":\"Gruppo Torelli Dottori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\",\"name\":\"Gruppo Torelli Dottori\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"width\":500,\"height\":214,\"caption\":\"Gruppo Torelli Dottori\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/person\\\/2f1f4289eb9b223ef8a647f8ebd6ebb4\",\"name\":\"admin_fliplab\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g\",\"caption\":\"admin_fliplab\"},\"sameAs\":[\"https:\\\/\\\/www.torellidottori.com\"],\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/author\\\/admin_fliplab\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Costruzioni antisismiche Torelli Dottori | Gruppo Torelli Dottori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/","og_locale":"it_IT","og_type":"article","og_title":"Costruzioni antisismiche Torelli Dottori | Gruppo Torelli Dottori","og_url":"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/","og_site_name":"Gruppo Torelli Dottori","article_published_time":"2022-04-07T13:37:44+00:00","article_modified_time":"2026-05-08T09:15:11+00:00","og_image":[{"width":433,"height":273,"url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-153729.webp","type":"image\/png"}],"author":"admin_fliplab","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin_fliplab","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/#article","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/"},"author":{"name":"admin_fliplab","@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/person\/2f1f4289eb9b223ef8a647f8ebd6ebb4"},"headline":"Costruzioni antisismiche Torelli Dottori","datePublished":"2022-04-07T13:37:44+00:00","dateModified":"2026-05-08T09:15:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/"},"wordCount":15,"publisher":{"@id":"https:\/\/www.torellidottori.com\/it\/#organization"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-153729.webp","inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/","url":"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/","name":"Costruzioni antisismiche Torelli Dottori | Gruppo Torelli Dottori","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/#primaryimage"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-153729.webp","datePublished":"2022-04-07T13:37:44+00:00","dateModified":"2026-05-08T09:15:11+00:00","breadcrumb":{"@id":"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/#primaryimage","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-153729.webp","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-153729.webp","width":433,"height":273},{"@type":"BreadcrumbList","@id":"https:\/\/www.torellidottori.com\/it\/costruzioni-antisismiche-torelli-dottori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.torellidottori.com\/it\/"},{"@type":"ListItem","position":2,"name":"Costruzioni antisismiche Torelli Dottori"}]},{"@type":"WebSite","@id":"https:\/\/www.torellidottori.com\/it\/#website","url":"https:\/\/www.torellidottori.com\/it\/","name":"Gruppo Torelli Dottori","description":"","publisher":{"@id":"https:\/\/www.torellidottori.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.torellidottori.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.torellidottori.com\/it\/#organization","name":"Gruppo Torelli Dottori","url":"https:\/\/www.torellidottori.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","width":500,"height":214,"caption":"Gruppo Torelli Dottori"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/person\/2f1f4289eb9b223ef8a647f8ebd6ebb4","name":"admin_fliplab","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g","caption":"admin_fliplab"},"sameAs":["https:\/\/www.torellidottori.com"],"url":"https:\/\/www.torellidottori.com\/it\/author\/admin_fliplab\/"}]}},"mfb_rest_fields":["title","blocksy_meta","yoast_head","yoast_head_json"],"_links":{"self":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/posts\/1860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/comments?post=1860"}],"version-history":[{"count":0,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/posts\/1860\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/media\/1862"}],"wp:attachment":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/media?parent=1860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/categories?post=1860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/tags?post=1860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}