{"id":1813,"date":"2018-10-07T12:20:38","date_gmt":"2018-10-07T10:20:38","guid":{"rendered":"https:\/\/www.torellidottori.com\/?p=1813"},"modified":"2026-05-08T11:15:11","modified_gmt":"2026-05-08T09:15:11","slug":"viaggio-castello-di-postignano","status":"publish","type":"post","link":"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/","title":{"rendered":"Viaggio Castello di Postignano"},"content":{"rendered":"\n<p>Postignano, castello di pendio del secolo XIII \u2013 ma con origine probabili nel IX \u2013 di impianto triangolare con vertice a monte costituito da una torre esagonale, domina la valle del Vigi e la strada che conduce a Spoleto.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2018.10_Viaggio-Castello-di-Postignano.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incorporamento di 2018.10_Viaggio Castello di Postignano.\"><\/object><a class=\"wp-element-button\" id=\"wp-block-file--media-0c1d6a2b-c208-4743-a7a1-e2226ab4541f\" href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2018.10_Viaggio-Castello-di-Postignano.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Visualizza<\/a><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2018.10_Viaggio-Castello-di-Postignano.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-0c1d6a2b-c208-4743-a7a1-e2226ab4541f\">Scarica l&#8217;articolo<\/a><\/div>\n\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider stk-block stk-b8e5656\" data-block-id=\"b8e5656\"><style>.stk-b8e5656 hr.stk-block-divider__hr{background:var(--theme-palette-color-5, #e1e8ed) !important;height:2px !important;width:100% !important;}.stk-b8e5656 {padding-top:var(--stk--preset--spacing--60, 2.25rem) !important;padding-bottom:var(--stk--preset--spacing--60, 2.25rem) !important;}<\/style><hr class=\"stk-block-divider__hr\"\/><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-ec8efb1\" id=\"scopri-il-progetto-realizzato\" data-block-id=\"ec8efb1\"><h4 class=\"stk-block-heading__text\">Scopri il progetto realizzato<\/h4><\/div>\n\n\n\n<div class=\"wp-block-query is-layout-flow wp-block-query-is-layout-flow\"><ul class=\"wp-block-post-template is-layout-flow wp-block-post-template-is-layout-flow\"><li class=\"wp-block-post post-1208 project type-project status-publish has-post-thumbnail hentry project-category-restauri\">\n\n<div class=\"wp-block-columns are-vertically-aligned-center has-palette-color-8-background-color has-background is-layout-flex wp-container-core-columns-is-layout-85958d59 wp-block-columns-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--40);padding-right:var(--wp--preset--spacing--40);padding-bottom:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--40)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.torellidottori.com\/it\/project\/borgo-medioevale-di-postignano\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/P1030620.webp\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Borgo Medioevale di Postignano\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/P1030620.webp 1280w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/P1030620-720x540.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/P1030620-768x576.webp 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\"><h4 class=\"wp-block-post-title\"><a href=\"https:\/\/www.torellidottori.com\/it\/project\/borgo-medioevale-di-postignano\/\" target=\"_self\" >Borgo Medioevale di Postignano<\/a><\/h4><\/div>\n<\/div>\n\n<\/li><\/ul><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postignano, castello di pendio del secolo XIII \u2013 ma con origine probabili nel IX \u2013 di impianto triangolare con vertice a monte costituito da una torre esagonale, domina la valle del Vigi e la strada che conduce a Spoleto. Scopri il progetto realizzato<\/p>\n","protected":false},"author":1,"featured_media":1209,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-1813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"blocksy_meta":[],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viaggio Castello di Postignano | Gruppo Torelli Dottori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viaggio Castello di Postignano | Gruppo Torelli Dottori\" \/>\n<meta property=\"og:description\" content=\"Postignano, castello di pendio del secolo XIII \u2013 ma con origine probabili nel IX \u2013 di impianto triangolare con vertice a monte costituito da una torre esagonale, domina la valle del Vigi e la strada che conduce a Spoleto. Scopri il progetto realizzato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/\" \/>\n<meta property=\"og:site_name\" content=\"Gruppo Torelli Dottori\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-07T10:20:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T09:15:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/P1030620.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_fliplab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_fliplab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/viaggio-castello-di-postignano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/viaggio-castello-di-postignano\\\/\"},\"author\":{\"name\":\"admin_fliplab\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/person\\\/2f1f4289eb9b223ef8a647f8ebd6ebb4\"},\"headline\":\"Viaggio Castello di Postignano\",\"datePublished\":\"2018-10-07T10:20:38+00:00\",\"dateModified\":\"2026-05-08T09:15:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/viaggio-castello-di-postignano\\\/\"},\"wordCount\":52,\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/viaggio-castello-di-postignano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/P1030620.webp\",\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/viaggio-castello-di-postignano\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/viaggio-castello-di-postignano\\\/\",\"name\":\"Viaggio Castello di Postignano | Gruppo Torelli Dottori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/viaggio-castello-di-postignano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/viaggio-castello-di-postignano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/P1030620.webp\",\"datePublished\":\"2018-10-07T10:20:38+00:00\",\"dateModified\":\"2026-05-08T09:15:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/viaggio-castello-di-postignano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/viaggio-castello-di-postignano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/viaggio-castello-di-postignano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/P1030620.webp\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/P1030620.webp\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/viaggio-castello-di-postignano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viaggio Castello di Postignano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\",\"name\":\"Gruppo Torelli Dottori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\",\"name\":\"Gruppo Torelli Dottori\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"width\":500,\"height\":214,\"caption\":\"Gruppo Torelli Dottori\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/person\\\/2f1f4289eb9b223ef8a647f8ebd6ebb4\",\"name\":\"admin_fliplab\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g\",\"caption\":\"admin_fliplab\"},\"sameAs\":[\"https:\\\/\\\/www.torellidottori.com\"],\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/author\\\/admin_fliplab\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viaggio Castello di Postignano | Gruppo Torelli Dottori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/","og_locale":"it_IT","og_type":"article","og_title":"Viaggio Castello di Postignano | Gruppo Torelli Dottori","og_description":"Postignano, castello di pendio del secolo XIII \u2013 ma con origine probabili nel IX \u2013 di impianto triangolare con vertice a monte costituito da una torre esagonale, domina la valle del Vigi e la strada che conduce a Spoleto. Scopri il progetto realizzato","og_url":"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/","og_site_name":"Gruppo Torelli Dottori","article_published_time":"2018-10-07T10:20:38+00:00","article_modified_time":"2026-05-08T09:15:11+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/P1030620.webp","type":"image\/jpeg"}],"author":"admin_fliplab","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin_fliplab","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/#article","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/"},"author":{"name":"admin_fliplab","@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/person\/2f1f4289eb9b223ef8a647f8ebd6ebb4"},"headline":"Viaggio Castello di Postignano","datePublished":"2018-10-07T10:20:38+00:00","dateModified":"2026-05-08T09:15:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/"},"wordCount":52,"publisher":{"@id":"https:\/\/www.torellidottori.com\/it\/#organization"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/P1030620.webp","inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/","url":"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/","name":"Viaggio Castello di Postignano | Gruppo Torelli Dottori","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/#primaryimage"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/P1030620.webp","datePublished":"2018-10-07T10:20:38+00:00","dateModified":"2026-05-08T09:15:11+00:00","breadcrumb":{"@id":"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/#primaryimage","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/P1030620.webp","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/P1030620.webp","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/www.torellidottori.com\/it\/viaggio-castello-di-postignano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.torellidottori.com\/it\/"},{"@type":"ListItem","position":2,"name":"Viaggio Castello di Postignano"}]},{"@type":"WebSite","@id":"https:\/\/www.torellidottori.com\/it\/#website","url":"https:\/\/www.torellidottori.com\/it\/","name":"Gruppo Torelli Dottori","description":"","publisher":{"@id":"https:\/\/www.torellidottori.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.torellidottori.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.torellidottori.com\/it\/#organization","name":"Gruppo Torelli Dottori","url":"https:\/\/www.torellidottori.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","width":500,"height":214,"caption":"Gruppo Torelli Dottori"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/person\/2f1f4289eb9b223ef8a647f8ebd6ebb4","name":"admin_fliplab","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g","caption":"admin_fliplab"},"sameAs":["https:\/\/www.torellidottori.com"],"url":"https:\/\/www.torellidottori.com\/it\/author\/admin_fliplab\/"}]}},"mfb_rest_fields":["title","blocksy_meta","yoast_head","yoast_head_json"],"_links":{"self":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/posts\/1813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/comments?post=1813"}],"version-history":[{"count":0,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/posts\/1813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/media\/1209"}],"wp:attachment":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/media?parent=1813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/categories?post=1813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/tags?post=1813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}