{"id":838,"date":"2026-01-13T15:37:03","date_gmt":"2026-01-13T14:37:03","guid":{"rendered":"https:\/\/www.torellidottori.com\/?page_id=838"},"modified":"2026-05-08T11:26:33","modified_gmt":"2026-05-08T09:26:33","slug":"lavora-con-noi","status":"publish","type":"page","link":"https:\/\/www.torellidottori.com\/it\/lavora-con-noi\/","title":{"rendered":"Lavora con noi"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-b19e7c9 stk-block-background stk--has-background-overlay\" data-block-id=\"b19e7c9\"><style>.stk-b19e7c9 {background-color:#555555 !important;background-image:url(https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/02\/Texture-w-1920-crop.svg) !important;padding-top:120px !important;padding-bottom:0px !important;margin-bottom:0px !important;overflow:visible !important;}.stk-b19e7c9:before{background-color:#555555 !important;opacity:0.8 !important;}.stk-b19e7c9 .stk-container{overflow:visible !important;}@media screen and (max-width:999px){.stk-b19e7c9 {padding-top:80px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-b19e7c9-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-da68494\" data-v=\"4\" data-block-id=\"da68494\"><style>.stk-da68494-container{margin-top:0px !important;margin-right:0px !important;margin-bottom:0px !important;margin-left:0px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-da68494-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-da68494-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-e3160ae\" data-block-id=\"e3160ae\"><style>.stk-e3160ae {height:90px !important;}@media screen and (max-width:999px){.stk-e3160ae {height:80px !important;}}<\/style><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-e10f9ca\" id=\"lavora-con-noi\" data-block-id=\"e10f9ca\"><style>.stk-e10f9ca {margin-bottom:0px !important;}.stk-e10f9ca .stk-block-heading__text{font-size:75px !important;color:var(--theme-palette-color-8, #ffffff) !important;line-height:1.3em !important;}@media screen and (max-width:999px){.stk-e10f9ca .stk-block-heading__text{font-size:50px !important;}}<\/style><h2 class=\"stk-block-heading__text has-text-color has-palette-color-8-color has-text-align-center\">Lavora con noi<\/h2><\/div>\n\n\n\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-1301428\" data-block-id=\"1301428\"><style>.stk-1301428 {height:70px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-b48aa69\" data-block-id=\"b48aa69\"><style>.stk-b48aa69 {height:120px !important;}@media screen and (max-width:999px){.stk-b48aa69 {height:80px !important;}}<\/style><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-5b0d21f\" data-block-id=\"5b0d21f\"><style>.stk-5b0d21f .stk--block-align-5b0d21f{align-items:flex-start !important;}.stk-5b0d21f {margin-bottom:0px !important;}.stk-5b0d21f-column{--stk-column-gap:50px !important;row-gap:50px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-5b0d21f stk-block-content stk-content-align stk-5b0d21f-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-2b62231\" data-v=\"4\" data-block-id=\"2b62231\"><style>.stk-2b62231-container{margin-top:0px !important;margin-right:0px !important;margin-bottom:0px !important;margin-left:0px !important;}@media screen and (min-width:690px){.stk-2b62231 {flex:var(--stk-flex-grow, 1) 1 calc(50% - var(--stk-column-gap, 0px) * 1 \/ 2 ) !important;}}@media screen and (min-width:690px) and (max-width:999px){.stk-2b62231 {flex:var(--stk-flex-grow, 1) 1 calc(100% - var(--stk-column-gap, 0px) * 0 \/ 1 ) !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-2b62231-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-2b62231-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-210582c\" id=\"siamo-alla-continua-ricerca-di-nuove-figure-per-la-crescita-del-nostro-gruppo\" data-block-id=\"210582c\"><style>.stk-210582c .stk-block-heading__bottom-line{background-color:var(--theme-palette-color-1, #FE5200) !important;}.stk-210582c .stk-block-heading__text{line-height:1.3em !important;}@media screen and (max-width:999px){.stk-210582c .stk-block-heading__text{font-size:30px !important;}}<\/style><h2 class=\"stk-block-heading__text has-text-align-left-tablet stk-block-heading--use-theme-margins\">Siamo alla continua ricerca di nuove figure per la crescita del nostro gruppo<\/h2><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-7e96063\" data-v=\"4\" data-block-id=\"7e96063\"><style>.stk-7e96063-container{margin-top:0px !important;margin-right:0px !important;margin-bottom:0px !important;margin-left:0px !important;}@media screen and (min-width:690px){.stk-7e96063 {flex:var(--stk-flex-grow, 1) 1 calc(50% - var(--stk-column-gap, 0px) * 1 \/ 2 ) !important;}}@media screen and (min-width:690px) and (max-width:999px){.stk-7e96063 {flex:var(--stk-flex-grow, 1) 1 calc(100% - var(--stk-column-gap, 0px) * 0 \/ 1 ) !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-7e96063-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-7e96063-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-11cfca1\" id=\"candidature-spontanee\" data-block-id=\"11cfca1\"><style>.stk-11cfca1 {margin-bottom:15px !important;}<\/style><h5 class=\"stk-block-heading__text has-text-align-left-tablet stk-block-heading--use-theme-margins\">Candidature spontanee<\/h5><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-f19ffa8\" data-block-id=\"f19ffa8\"><p class=\"stk-block-text__text has-text-align-left-tablet\">La nostra impresa accoglie con interesse candidature spontanee per ruoli operativi, tecnici e amministrativi. Valutiamo profili qualificati che possano contribuire con professionalit\u00e0 e responsabilit\u00e0 allo sviluppo delle attivit\u00e0 aziendali.<\/p><\/div>\n\n\n\n<p>Crediamo nell\u2019inserimento strutturato delle risorse e investiamo nella loro crescita attraverso formazione interna sui processi aziendali, affiancamento operativo e percorsi tecnici dedicati, realizzati con il supporto di consulenti e fornitori specializzati.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-4efe46f\" data-block-id=\"4efe46f\"><style>.stk-4efe46f {height:120px !important;}@media screen and (max-width:999px){.stk-4efe46f {height:80px !important;}}<\/style><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-b37a76a\" data-block-id=\"b37a76a\"><style>.stk-b37a76a .stk--block-align-b37a76a{align-items:center !important;}.stk-b37a76a {margin-bottom:0px !important;}.stk-b37a76a-column{--stk-column-gap:300px !important;row-gap:30px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-b37a76a stk-block-content stk-content-align stk-b37a76a-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-01fbabe\" data-v=\"4\" data-block-id=\"01fbabe\"><style>.stk-01fbabe-container{margin-top:0px !important;margin-right:0px !important;margin-bottom:0px !important;margin-left:0px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-01fbabe-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-01fbabe-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-bd3d97a\" id=\"invia-una-candidatura\" data-block-id=\"bd3d97a\"><style>.stk-bd3d97a .stk-block-heading__bottom-line{background-color:var(--theme-palette-color-1, #FE5200) !important;}.stk-bd3d97a .stk-block-heading__text{font-size:40px !important;line-height:1.3em !important;}@media screen and (max-width:999px){.stk-bd3d97a .stk-block-heading__text{font-size:30px !important;}}<\/style><h3 class=\"stk-block-heading__text has-text-align-left-tablet stk-block-heading--use-theme-margins\">Invia una candidatura<\/h3><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-70e6248\" data-block-id=\"70e6248\"><style>.stk-70e6248 .stk-block-text__text{font-size:20px !important;color:var(--theme-palette-color-4, #0A1821) !important;font-weight:700 !important;}@media screen and (max-width:999px){.stk-70e6248 .stk-block-text__text{font-size:20px !important;}}<\/style><p class=\"stk-block-text__text has-text-color has-palette-color-4-color has-text-align-left-tablet\">Compila il form con i tuoi dati e allega il tuo curriculum<\/p><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-4efad20\" data-block-id=\"4efad20\"><style>.stk-4efad20 {height:70px !important;border-style:solid !important;border-color:var(--theme-palette-color-5, #F2F2F2) !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:2px !important;border-left-width:0px !important;}@media screen and (max-width:999px){.stk-4efad20 {height:50px !important;}}<\/style><\/div>\n\n\n\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-a542482\" data-block-id=\"a542482\"><style>.stk-a542482 {height:70px !important;}@media screen and (max-width:999px){.stk-a542482 {height:50px !important;}}<\/style><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8767c9e\" data-block-id=\"8767c9e\"><style>.stk-8767c9e {margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-8767c9e-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-3394de0 stk-block-background\" data-v=\"4\" data-block-id=\"3394de0\"><style>.stk-3394de0 {background-color:var(--theme-palette-color-8, #ffffff) !important;box-shadow:0px 12px 16px -6px #2238650a !important;padding-top:55px !important;padding-right:50px !important;padding-bottom:55px !important;padding-left:50px !important;}.stk-3394de0:before{background-color:var(--theme-palette-color-8, #ffffff) !important;}@media screen and (max-width:999px){.stk-3394de0 {padding-top:40px !important;padding-right:40px !important;padding-bottom:40px !important;padding-left:40px !important;}}@media screen and (max-width:689px){.stk-3394de0 {padding-top:24px !important;padding-right:24px !important;padding-bottom:24px !important;padding-left:24px !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-3394de0-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-3394de0-inner-blocks\">\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f910-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"910\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/838#wpcf7-f910-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Modulo di contatto\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"910\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f910-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"col-container\">\n    <div class=\"one-half\">\n    <label> Nome *\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n    <\/div>\n    <div class=\"one-half\">\n    <label> Cognome *\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"surname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"surname\" \/><\/span> <\/label>\n    <\/div>\n    <div class=\"one-half\">\n    <label> Email *\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n    <\/div>\n    <div class=\"one-half\">\n    <label> Telefono *\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"telefono\" \/><\/span> <\/label>\n    <\/div>\n    <div class=\"one-full\">\n    <label> Allega CV *\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"cv\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file wpcf7-validates-as-required\" accept=\".pdf,.doc,.docx,.odt,.zip,.rar\" aria-required=\"true\" aria-invalid=\"false\" type=\"file\" name=\"cv\" \/><\/span>\n        <small>Max. dimensione file 3Mb - Formati file ammessi pdf, doc, docx, odt, zip, rar<\/span> \n    <\/label>\n    <\/div>\n<\/div>\n<label> Messaggio *\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"4\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n\n<span class=\"wpcf7-form-control-wrap\" data-name=\"privacy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"privacy\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">* Acconsento al trattamento e alla comunicazione dei miei dati personali, in conformit\u00e0 a quanto esposto e descritto nella <a href=\"\/privacy-policy\" target=\"_blank\" tabindex=\"-1\">Privacy Policy<\/a>. Dichiaro di averne preso visione e autorizzo Torelli Dottori S.P.A. in via esclusiva al trattamento dei dati dichiarati. Tutti i dati personali saranno trattati ai sensi degli articoli 13 e 14 del Regolamento UE 679\/2016 (GDPR) per le finalit\u00e0 dichiarate.<\/span><\/label><\/span><\/span><\/span>\n\n<div class=\"wpcf7-turnstile cf-turnstile\" data-sitekey=\"0x4AAAAAADNLVv-5M9TLyt-N\" data-response-field-name=\"_wpcf7_turnstile_response\"><\/div>\n\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"INVIA\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Form Lavora con noi\" type=\"hidden\" name=\"your-subject\" \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-8486660\" data-block-id=\"8486660\"><style>.stk-8486660 {height:120px !important;}@media screen and (max-width:999px){.stk-8486660 {height:80px !important;}}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lavora con noi Siamo alla continua ricerca di nuove figure per la crescita del nostro gruppo Candidature spontanee La nostra impresa accoglie con interesse candidature spontanee per ruoli operativi, tecnici e amministrativi. Valutiamo profili qualificati che possano contribuire con professionalit\u00e0 e responsabilit\u00e0 allo sviluppo delle attivit\u00e0 aziendali. Crediamo nell\u2019inserimento strutturato delle risorse e investiamo nella [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-838","page","type-page","status-publish","hentry"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6},"page_title_panel":"","has_hero_section":"disabled","cdffe435dcab9bc0ccfb8b8286615cd0":"","hero_section":"type-1","hero_elements":[{"id":"custom_title","enabled":true,"heading_tag":"h1","title":"Home"},{"id":"custom_description","enabled":true,"description_visibility":{"desktop":true,"tablet":true,"mobile":false}},{"id":"custom_meta","enabled":false,"meta_elements":[{"id":"author","enabled":true,"label":"By","has_author_avatar":"yes","avatar_size":25},{"id":"post_date","enabled":true,"label":"On","date_format_source":"default","date_format":"M j, Y"},{"id":"updated_date","enabled":false,"label":"On","date_format_source":"default","date_format":"M j, Y"},{"id":"categories","enabled":false,"label":"In","style":"simple"},{"id":"comments","enabled":true}],"page_meta_elements":{"joined":true,"articles_count":true,"comments":true}},{"id":"breadcrumbs","enabled":false}],"aa3e71982d0f17b8fe2bfbbbb3812215":"","hero_alignment1":"CT_CSS_SKIP_RULE","hero_margin":40,"hero_alignment2":"center","hero_vertical_alignment":"center","e60ee0ea9b28fd15f57bf213bf429eae":"","hero_structure":"narrow","91f1b2d6092ab8cac63a7d09191e2915":"","page_title_bg_type":"featured_image","custom_hero_background":{"attachment_id":null},"page_title_image_size":"full","parallax":{"desktop":false,"tablet":false,"mobile":false},"3b731d17b6531211b1472abeefaae46a":"","hero_height":"250px","pageTitleFont":{"family":"Default","variation":"Default","size":"30px","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"pageTitleFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageMetaFont":{"family":"Default","variation":"n6","size":"12px","line-height":"1.3","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"uppercase","text-decoration":"CT_CSS_SKIP_RULE"},"pageMetaFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"page_meta_button_type_font_colors":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"page_meta_button_type_background_colors":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageExcerptFont":{"family":"Default","variation":"Default","size":"CT_CSS_SKIP_RULE","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"pageExcerptColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"breadcrumbsFont":{"family":"Default","variation":"Default","size":"CT_CSS_SKIP_RULE","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"breadcrumbsFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"initial":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageTitleOverlay":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"CT_CSS_SKIP_RULE"}}},"pageTitleBackground":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"var(--theme-palette-color-6)"}}},"pageTitlePadding":{"top":"50px","bottom":"50px","left":"auto","right":"auto","linked":true},"dc538ce9b4da84cfb0fa32d6a20988f8":"","page_structure_type":"default","24b6769498b19f76af1dd253e1cc607f":"","content_style_source":"inherit","content_style":"wide","vertical_spacing_source":"custom","content_area_spacing":"none","background":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"CT_CSS_SKIP_RULE"}}},"content_background":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"var(--theme-palette-color-8)"}}},"content_boxed_shadow":{"inherit":false,"blur":18,"spread":-6,"v_offset":12,"h_offset":0,"inset":false,"enable":true,"color":{"color":"rgba(34, 56, 101, 0.04)"}},"content_boxed_border":{"width":1,"style":"none","color":{"color":"rgba(44,62,80,0.2)"}},"content_boxed_radius":{"top":"3px","bottom":"3px","left":"3px","right":"3px","linked":true},"boxed_content_spacing":{"desktop":{"top":"40px","bottom":"40px","left":"40px","right":"40px","linked":true},"tablet":{"top":"35px","bottom":"35px","left":"35px","right":"35px","linked":true},"mobile":{"top":"20px","bottom":"20px","left":"20px","right":"20px","linked":true}},"ac93a16d09c08770d93e1a1ae1cdc52e":"","disable_featured_image":"no","disable_share_box":"no","disable_header":"no","disable_footer":"no"},"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lavora con noi | Gruppo Torelli Dottori<\/title>\n<meta name=\"description\" content=\"Siamo alla continua ricerca di nuove figure per la crescita del nostro gruppo. Invia la tua candidatura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.torellidottori.com\/it\/lavora-con-noi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lavora con noi | Gruppo Torelli Dottori\" \/>\n<meta property=\"og:description\" content=\"Siamo alla continua ricerca di nuove figure per la crescita del nostro gruppo. Invia la tua candidatura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.torellidottori.com\/it\/lavora-con-noi\/\" \/>\n<meta property=\"og:site_name\" content=\"Gruppo Torelli Dottori\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T09:26:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/01\/IMG_5561_bw.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/lavora-con-noi\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/lavora-con-noi\\\/\",\"name\":\"Lavora con noi | Gruppo Torelli Dottori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#website\"},\"datePublished\":\"2026-01-13T14:37:03+00:00\",\"dateModified\":\"2026-05-08T09:26:33+00:00\",\"description\":\"Siamo alla continua ricerca di nuove figure per la crescita del nostro gruppo. Invia la tua candidatura.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/lavora-con-noi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/lavora-con-noi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/lavora-con-noi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lavora con noi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\",\"name\":\"Gruppo Torelli Dottori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#organization\",\"name\":\"Gruppo Torelli Dottori\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"width\":500,\"height\":214,\"caption\":\"Gruppo Torelli Dottori\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lavora con noi | Gruppo Torelli Dottori","description":"Siamo alla continua ricerca di nuove figure per la crescita del nostro gruppo. Invia la tua candidatura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.torellidottori.com\/it\/lavora-con-noi\/","og_locale":"it_IT","og_type":"article","og_title":"Lavora con noi | Gruppo Torelli Dottori","og_description":"Siamo alla continua ricerca di nuove figure per la crescita del nostro gruppo. Invia la tua candidatura.","og_url":"https:\/\/www.torellidottori.com\/it\/lavora-con-noi\/","og_site_name":"Gruppo Torelli Dottori","article_modified_time":"2026-05-08T09:26:33+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/01\/IMG_5561_bw.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.torellidottori.com\/it\/lavora-con-noi\/","url":"https:\/\/www.torellidottori.com\/it\/lavora-con-noi\/","name":"Lavora con noi | Gruppo Torelli Dottori","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/it\/#website"},"datePublished":"2026-01-13T14:37:03+00:00","dateModified":"2026-05-08T09:26:33+00:00","description":"Siamo alla continua ricerca di nuove figure per la crescita del nostro gruppo. Invia la tua candidatura.","breadcrumb":{"@id":"https:\/\/www.torellidottori.com\/it\/lavora-con-noi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.torellidottori.com\/it\/lavora-con-noi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.torellidottori.com\/it\/lavora-con-noi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.torellidottori.com\/it\/"},{"@type":"ListItem","position":2,"name":"Lavora con noi"}]},{"@type":"WebSite","@id":"https:\/\/www.torellidottori.com\/it\/#website","url":"https:\/\/www.torellidottori.com\/it\/","name":"Gruppo Torelli Dottori","description":"","publisher":{"@id":"https:\/\/www.torellidottori.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.torellidottori.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.torellidottori.com\/it\/#organization","name":"Gruppo Torelli Dottori","url":"https:\/\/www.torellidottori.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","width":500,"height":214,"caption":"Gruppo Torelli Dottori"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/#\/schema\/logo\/image\/"}}]}},"mfb_rest_fields":["title","blocksy_meta","yoast_head","yoast_head_json"],"_links":{"self":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/pages\/838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/comments?post=838"}],"version-history":[{"count":0,"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/pages\/838\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.torellidottori.com\/it\/wp-json\/wp\/v2\/media?parent=838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}