{"id":2543,"date":"2026-03-30T12:25:18","date_gmt":"2026-03-30T10:25:18","guid":{"rendered":"https:\/\/www.torellidottori.com\/project\/coincasa\/"},"modified":"2026-05-05T17:54:22","modified_gmt":"2026-05-05T15:54:22","slug":"coincasa","status":"publish","type":"project","link":"https:\/\/www.torellidottori.com\/en\/project\/coincasa\/","title":{"rendered":"Coincasa"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-1a28912 stk-block-background\" data-block-id=\"1a28912\"><style>.stk-1a28912 {background-color:var(--theme-palette-color-8, #ffffff) !important;padding-top:120px !important;padding-right:0px !important;padding-bottom:20px !important;padding-left:0px !important;margin-bottom:0px !important;}.stk-1a28912:before{background-color:var(--theme-palette-color-8, #ffffff) !important;}.stk-1a28912-column{--stk-columns-spacing:0px !important;--stk-column-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}@media screen and (max-width:689px){.stk-1a28912 {padding-top:60px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-1a28912-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-7b461d9\" data-v=\"4\" data-block-id=\"7b461d9\"><style>@media screen and (min-width:690px){.stk-7b461d9 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-7b461d9-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-7b461d9-inner-blocks\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/IMG_5311-scaled.webp\" alt=\"\" class=\"wp-image-1671\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/IMG_5311-scaled.webp 2560w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/IMG_5311-720x480.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/IMG_5311-1920x1280.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/IMG_5311-768x512.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/IMG_5311-1536x1024.webp 1536w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/IMG_5311-2048x1365.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ea3d3f5\" data-v=\"4\" data-block-id=\"ea3d3f5\"><style>.stk-ea3d3f5 {box-shadow:0px 12px 16px -6px #2339662e !important;border-style:solid !important;border-color:var(--theme-palette-color-1, #FE5200) !important;border-top-width:4px !important;border-right-width:0px !important;border-bottom-width:0px !important;border-left-width:0px !important;}@media screen and (min-width:690px){.stk-ea3d3f5 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}@media screen and (max-width:999px){.stk-ea3d3f5 {margin-top:60px !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ea3d3f5-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ea3d3f5-inner-blocks\">\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-aacc673\" data-block-id=\"aacc673\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-aacc673-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-77b4e76\" data-v=\"4\" data-block-id=\"77b4e76\"><style>.stk-77b4e76-container{margin-top:30px !important;margin-right:30px !important;margin-bottom:30px !important;margin-left:30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-77b4e76-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-77b4e76-inner-blocks\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-fe9cc265 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group w-100 is-layout-constrained wp-block-group-is-layout-constrained\" style=\"border-bottom-color:var(--wp--preset--color--palette-color-5);border-bottom-width:2px;padding-bottom:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-fce8432\" id=\"marchio\" data-block-id=\"fce8432\"><style>.stk-fce8432 {margin-bottom:16px !important;}.stk-fce8432 .stk-block-heading__text{text-transform:uppercase !important;}<\/style><h6 class=\"stk-block-heading__text\">BRAND:<\/h6><\/div>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"219\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/Logo-Coincasa.webp\" alt=\"\" class=\"wp-image-1663\" style=\"width:auto;height:60px\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/Logo-Coincasa.webp 900w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/Logo-Coincasa-720x175.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/Logo-Coincasa-768x187.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-group w-100 is-layout-constrained wp-block-group-is-layout-constrained\" style=\"border-bottom-color:var(--wp--preset--color--palette-color-5);border-bottom-width:2px\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-83d95e21 wp-block-group-is-layout-flex\" style=\"padding-right:0;padding-bottom:var(--wp--preset--spacing--50);padding-left:0\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-43e8ac2\" id=\"ambito\" data-block-id=\"43e8ac2\"><style>.stk-43e8ac2 {margin-bottom:0px !important;}.stk-43e8ac2 .stk-block-heading__text{text-transform:uppercase !important;}<\/style><h6 class=\"stk-block-heading__text\">Sector:<\/h6><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-ade8aa9\" data-block-id=\"ade8aa9\"><style>.stk-ade8aa9 {margin-bottom:0px !important;}<\/style><p class=\"stk-block-text__text\">Home furnishings and linens<\/p><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-b1895f4f wp-block-group-is-layout-flex\" style=\"padding-right:0;padding-left:0\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-574b6e3\" id=\"localita\" data-block-id=\"574b6e3\"><style>.stk-574b6e3 {margin-bottom:0px !important;}.stk-574b6e3 .stk-block-heading__text{text-transform:uppercase !important;}<\/style><h6 class=\"stk-block-heading__text\">Location:<\/h6><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-6dc8795\" data-block-id=\"6dc8795\"><style>.stk-6dc8795 {margin-bottom:0px !important;}<\/style><p class=\"stk-block-text__text\">Urbino c\/o Parco Commerciale Consorzio<\/p><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-91319a5 stk-block-background\" data-block-id=\"91319a5\"><style>.stk-91319a5 {background-color:var(--theme-palette-color-8, #ffffff) !important;padding-top:90px !important;padding-bottom:90px !important;}.stk-91319a5:before{background-color:var(--theme-palette-color-8, #ffffff) !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-91319a5-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c5c2d2a\" data-v=\"4\" data-block-id=\"c5c2d2a\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c5c2d2a-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c5c2d2a-inner-blocks\">\n<figure class=\"wp-block-gallery has-nested-images columns-5 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6511-scaled.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" data-id=\"1670\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6511-scaled.webp\" alt=\"\" class=\"wp-image-1670\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6511-scaled.webp 2560w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6511-720x480.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6511-1920x1280.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6511-768x512.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6511-1536x1024.webp 1536w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6511-2048x1365.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6505-scaled.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" data-id=\"1669\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6505-scaled.webp\" alt=\"\" class=\"wp-image-1669\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6505-scaled.webp 2560w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6505-720x480.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6505-1920x1280.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6505-768x512.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6505-1536x1024.webp 1536w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6505-2048x1365.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6504-scaled.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" data-id=\"1668\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6504-scaled.webp\" alt=\"\" class=\"wp-image-1668\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6504-scaled.webp 2560w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6504-720x480.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6504-1920x1280.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6504-768x512.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6504-1536x1024.webp 1536w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6504-2048x1365.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6503-scaled.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" data-id=\"1667\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6503-scaled.webp\" alt=\"\" class=\"wp-image-1667\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6503-scaled.webp 2560w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6503-720x480.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6503-1920x1280.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6503-768x512.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6503-1536x1024.webp 1536w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6503-2048x1365.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6497-scaled.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" data-id=\"1666\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6497-scaled.webp\" alt=\"\" class=\"wp-image-1666\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6497-scaled.webp 2560w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6497-720x480.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6497-1920x1280.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6497-768x512.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6497-1536x1024.webp 1536w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6497-2048x1365.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6488-scaled.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" data-id=\"1665\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6488-scaled.webp\" alt=\"\" class=\"wp-image-1665\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6488-scaled.webp 2560w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6488-720x480.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6488-1920x1280.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6488-768x512.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6488-1536x1024.webp 1536w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6488-2048x1365.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6486-scaled.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" data-id=\"1664\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6486-scaled.webp\" alt=\"\" class=\"wp-image-1664\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6486-scaled.webp 2560w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6486-720x480.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6486-1920x1280.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6486-768x512.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6486-1536x1024.webp 1536w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6486-2048x1365.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n<\/figure>\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"featured_media":2542,"menu_order":0,"template":"","meta":{"_acf_changed":false},"project-category":[32],"project-tag":[],"class_list":["post-2543","project","type-project","status-publish","has-post-thumbnail","hentry","project-category-our-stores-at-the-consorzio-shopping-center"],"blocksy_meta":[],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coincasa | Gruppo Torelli Dottori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.torellidottori.com\/en\/project\/coincasa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coincasa | Gruppo Torelli Dottori\" \/>\n<meta property=\"og:description\" content=\"BRAND: Sector: Home furnishings and linens Location: Urbino c\/o Parco Commerciale Consorzio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.torellidottori.com\/en\/project\/coincasa\/\" \/>\n<meta property=\"og:site_name\" content=\"Gruppo Torelli Dottori\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T15:54:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6486-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/coincasa\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/coincasa\\\/\",\"name\":\"Coincasa | Gruppo Torelli Dottori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/coincasa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/coincasa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/DSC_6486-scaled.webp\",\"datePublished\":\"2026-03-30T10:25:18+00:00\",\"dateModified\":\"2026-05-05T15:54:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/coincasa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/coincasa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/coincasa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/DSC_6486-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/DSC_6486-scaled.webp\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/coincasa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coincasa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/\",\"name\":\"Gruppo Torelli Dottori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#organization\",\"name\":\"Gruppo Torelli Dottori\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"width\":500,\"height\":214,\"caption\":\"Gruppo Torelli Dottori\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coincasa | Gruppo Torelli Dottori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.torellidottori.com\/en\/project\/coincasa\/","og_locale":"en_US","og_type":"article","og_title":"Coincasa | Gruppo Torelli Dottori","og_description":"BRAND: Sector: Home furnishings and linens Location: Urbino c\/o Parco Commerciale Consorzio","og_url":"https:\/\/www.torellidottori.com\/en\/project\/coincasa\/","og_site_name":"Gruppo Torelli Dottori","article_modified_time":"2026-05-05T15:54:22+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6486-scaled.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.torellidottori.com\/en\/project\/coincasa\/","url":"https:\/\/www.torellidottori.com\/en\/project\/coincasa\/","name":"Coincasa | Gruppo Torelli Dottori","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.torellidottori.com\/en\/project\/coincasa\/#primaryimage"},"image":{"@id":"https:\/\/www.torellidottori.com\/en\/project\/coincasa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6486-scaled.webp","datePublished":"2026-03-30T10:25:18+00:00","dateModified":"2026-05-05T15:54:22+00:00","breadcrumb":{"@id":"https:\/\/www.torellidottori.com\/en\/project\/coincasa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.torellidottori.com\/en\/project\/coincasa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.torellidottori.com\/en\/project\/coincasa\/#primaryimage","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6486-scaled.webp","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/DSC_6486-scaled.webp","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.torellidottori.com\/en\/project\/coincasa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.torellidottori.com\/en\/"},{"@type":"ListItem","position":2,"name":"Coincasa"}]},{"@type":"WebSite","@id":"https:\/\/www.torellidottori.com\/en\/#website","url":"https:\/\/www.torellidottori.com\/en\/","name":"Gruppo Torelli Dottori","description":"","publisher":{"@id":"https:\/\/www.torellidottori.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.torellidottori.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.torellidottori.com\/en\/#organization","name":"Gruppo Torelli Dottori","url":"https:\/\/www.torellidottori.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.torellidottori.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","width":500,"height":214,"caption":"Gruppo Torelli Dottori"},"image":{"@id":"https:\/\/www.torellidottori.com\/en\/#\/schema\/logo\/image\/"}}]}},"mfb_rest_fields":["title","blocksy_meta","yoast_head","yoast_head_json"],"_links":{"self":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/project\/2543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/media\/2542"}],"wp:attachment":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/media?parent=2543"}],"wp:term":[{"taxonomy":"project-category","embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/project-category?post=2543"},{"taxonomy":"project-tag","embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/project-tag?post=2543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}