{"id":2516,"date":"2026-03-31T15:07:11","date_gmt":"2026-03-31T13:07:11","guid":{"rendered":"https:\/\/www.torellidottori.com\/project\/consorzio-shopping-center\/"},"modified":"2026-05-05T17:50:30","modified_gmt":"2026-05-05T15:50:30","slug":"consorzio-shopping-center","status":"publish","type":"project","link":"https:\/\/www.torellidottori.com\/en\/project\/consorzio-shopping-center\/","title":{"rendered":"Consorzio Shopping Center"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-1a28912 stk-block-background\" data-block-id=\"1a28912\"><style>.stk-1a28912 {background-color:var(--theme-palette-color-8, #ffffff) !important;padding-top:120px !important;padding-right:0px !important;padding-bottom:20px !important;padding-left:0px !important;margin-bottom:0px !important;}.stk-1a28912:before{background-color:var(--theme-palette-color-8, #ffffff) !important;}.stk-1a28912-column{--stk-columns-spacing:0px !important;--stk-column-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}@media screen and (max-width:689px){.stk-1a28912 {padding-top:60px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-1a28912-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-7b461d9\" data-v=\"4\" data-block-id=\"7b461d9\"><style>@media screen and (min-width:690px){.stk-7b461d9 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-7b461d9-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-7b461d9-inner-blocks\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1585\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/001-scaled.webp\" alt=\"\" class=\"wp-image-1726\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/001-scaled.webp 2560w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/001-720x446.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/001-1920x1189.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/001-768x476.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/001-1536x951.webp 1536w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/001-2048x1268.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ea3d3f5\" data-v=\"4\" data-block-id=\"ea3d3f5\"><style>.stk-ea3d3f5 {box-shadow:0px 12px 16px -6px #2339662e !important;border-style:solid !important;border-color:var(--theme-palette-color-1, #FE5200) !important;border-top-width:4px !important;border-right-width:0px !important;border-bottom-width:0px !important;border-left-width:0px !important;}@media screen and (min-width:690px){.stk-ea3d3f5 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}@media screen and (max-width:999px){.stk-ea3d3f5 {margin-top:60px !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ea3d3f5-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ea3d3f5-inner-blocks\">\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-aacc673\" data-block-id=\"aacc673\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-aacc673-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-77b4e76\" data-v=\"4\" data-block-id=\"77b4e76\"><style>.stk-77b4e76-container{margin-top:30px !important;margin-right:30px !important;margin-bottom:30px !important;margin-left:30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-77b4e76-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-77b4e76-inner-blocks\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-fe9cc265 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group w-100 is-layout-constrained wp-block-group-is-layout-constrained\" style=\"border-bottom-color:var(--wp--preset--color--palette-color-5);border-bottom-width:2px;padding-bottom:var(--wp--preset--spacing--50)\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"901\" height=\"241\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/Immagine-2026-03-31-150515.webp\" alt=\"\" class=\"wp-image-1724\" style=\"width:auto;height:60px\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/Immagine-2026-03-31-150515.webp 901w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/Immagine-2026-03-31-150515-720x193.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/Immagine-2026-03-31-150515-768x205.webp 768w\" sizes=\"auto, (max-width: 901px) 100vw, 901px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-b1895f4f wp-block-group-is-layout-flex\" style=\"padding-right:0;padding-left:0\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-574b6e3\" id=\"localita\" data-block-id=\"574b6e3\"><style>.stk-574b6e3 {margin-bottom:0px !important;}.stk-574b6e3 .stk-block-heading__text{text-transform:uppercase !important;}<\/style><h6 class=\"stk-block-heading__text\">Location:<\/h6><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-6dc8795\" data-block-id=\"6dc8795\"><style>.stk-6dc8795 {margin-bottom:0px !important;}<\/style><p class=\"stk-block-text__text\">S.S. Bocca Trabaria Sud n. 2, Urbino (PU)<\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-b1895f4f wp-block-group-is-layout-flex\" style=\"padding-right:0;padding-left:0\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-c7f803c\" id=\"contatti\" data-block-id=\"c7f803c\"><style>.stk-c7f803c {margin-bottom:0px !important;}.stk-c7f803c .stk-block-heading__text{text-transform:uppercase !important;}<\/style><h6 class=\"stk-block-heading__text\">CONTACTS<\/h6><\/div>\n\n\n\n<p><a href=\"http:\/\/www.consorziocenter.com\" target=\"_blank\" rel=\"noreferrer noopener\">www.consorziocenter.com<\/a><\/p>\n\n\n<div class=\"ct-block-wrapper\" style=\"margin-top:var(--wp--preset--spacing--30);\">\n<div class=\"ct-socials-block\" style=\"--theme-icon-hover-color:var(--wp--preset--color--palette-color-1);--theme-icon-size:24px;\">\n\t\t<div class=\"ct-social-box\" data-color=\"default\" data-icons-type=\"simple\" style=\"\" >\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/www.facebook.com\/CentroCommercialeConsorzio\" data-network=\"facebook\" aria-label=\"Facebook\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\t\t<span class=\"ct-icon-container\">\n\t\t\t\t\t<svg\n\t\t\t\t\twidth=\"20px\"\n\t\t\t\t\theight=\"20px\"\n\t\t\t\t\tviewBox=\"0 0 20 20\"\n\t\t\t\t\taria-hidden=\"true\">\n\t\t\t\t\t\t<path d=\"M20,10.1c0-5.5-4.5-10-10-10S0,4.5,0,10.1c0,5,3.7,9.1,8.4,9.9v-7H5.9v-2.9h2.5V7.9C8.4,5.4,9.9,4,12.2,4c1.1,0,2.2,0.2,2.2,0.2v2.5h-1.3c-1.2,0-1.6,0.8-1.6,1.6v1.9h2.8L13.9,13h-2.3v7C16.3,19.2,20,15.1,20,10.1z\"\/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/span>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/www.instagram.com\/centrocomm_consorzio\/\" data-network=\"instagram\" aria-label=\"Instagram\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\t\t<span class=\"ct-icon-container\">\n\t\t\t\t\t<svg\n\t\t\t\t\twidth=\"20\"\n\t\t\t\t\theight=\"20\"\n\t\t\t\t\tviewBox=\"0 0 20 20\"\n\t\t\t\t\taria-hidden=\"true\">\n\t\t\t\t\t\t<circle cx=\"10\" cy=\"10\" r=\"3.3\"\/>\n\t\t\t\t\t\t<path d=\"M14.2,0H5.8C2.6,0,0,2.6,0,5.8v8.3C0,17.4,2.6,20,5.8,20h8.3c3.2,0,5.8-2.6,5.8-5.8V5.8C20,2.6,17.4,0,14.2,0zM10,15c-2.8,0-5-2.2-5-5s2.2-5,5-5s5,2.2,5,5S12.8,15,10,15z M15.8,5C15.4,5,15,4.6,15,4.2s0.4-0.8,0.8-0.8s0.8,0.4,0.8,0.8S16.3,5,15.8,5z\"\/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/span>\t\t\t\t<\/a>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-button-group stk-block-button-group stk-block stk-d1c5df2\" data-block-id=\"d1c5df2\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-button-group\">\n<div class=\"wp-block-stackable-button stk-block-button is-style-ghost stk-block stk-d7545ec\" data-block-id=\"d7545ec\"><style>.stk-d7545ec .stk-button{background:transparent !important;}.stk-d7545ec .stk-button:hover:after{background:transparent !important;opacity:1 !important;}:where(.stk-hover-parent:hover,  .stk-hover-parent.stk--is-hovered) .stk-d7545ec .stk-button:after{background:transparent !important;opacity:1 !important;}.stk-d7545ec .stk-button:before{border-style:solid !important;}<\/style><a class=\"stk-link stk-button stk--hover-effect-darken\" href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Depliant-Consorzio-04.2026.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"stk-button__inner-text\">DOWNLOAD THE BROCHURE<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-91319a5 stk-block-background\" data-block-id=\"91319a5\"><style>.stk-91319a5 {background-color:var(--theme-palette-color-8, #ffffff) !important;padding-top:90px !important;padding-bottom:90px !important;}.stk-91319a5:before{background-color:var(--theme-palette-color-8, #ffffff) !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-91319a5-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c5c2d2a\" data-v=\"4\" data-block-id=\"c5c2d2a\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c5c2d2a-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c5c2d2a-inner-blocks\">\n<figure class=\"wp-block-gallery has-nested-images columns-5 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/002-scaled.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1522\" data-id=\"1727\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/002-scaled.webp\" alt=\"\" class=\"wp-image-1727\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/002-scaled.webp 2560w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/002-720x428.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/002-1920x1141.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/002-768x457.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/002-1536x913.webp 1536w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/002-2048x1217.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/003-scaled.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" data-id=\"1728\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/003-scaled.webp\" alt=\"\" class=\"wp-image-1728\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/003-scaled.webp 2560w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/003-720x480.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/003-1920x1280.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/003-768x512.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/003-1536x1024.webp 1536w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/003-2048x1365.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/017-scaled.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1533\" data-id=\"1729\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/017-scaled.webp\" alt=\"\" class=\"wp-image-1729\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/017-scaled.webp 2560w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/017-720x431.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/017-1920x1149.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/017-768x460.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/017-1536x920.webp 1536w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/017-2048x1226.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/020-2-scaled.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1431\" data-id=\"1730\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/020-2-scaled.webp\" alt=\"\" class=\"wp-image-1730\" style=\"aspect-ratio:1\" srcset=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/020-2-scaled.webp 2560w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/020-2-720x403.webp 720w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/020-2-1920x1074.webp 1920w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/020-2-768x429.webp 768w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/020-2-1536x859.webp 1536w, https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/020-2-2048x1145.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n<\/figure>\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"featured_media":2515,"menu_order":0,"template":"","meta":{"_acf_changed":false},"project-category":[30],"project-tag":[],"class_list":["post-2516","project","type-project","status-publish","has-post-thumbnail","hentry","project-category-property-management"],"blocksy_meta":[],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consorzio Shopping Center | Gruppo Torelli Dottori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.torellidottori.com\/en\/project\/consorzio-shopping-center\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consorzio Shopping Center | Gruppo Torelli Dottori\" \/>\n<meta property=\"og:description\" content=\"Location: S.S. Bocca Trabaria Sud n. 2, Urbino (PU) CONTACTS www.consorziocenter.com DOWNLOAD THE BROCHURE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.torellidottori.com\/en\/project\/consorzio-shopping-center\/\" \/>\n<meta property=\"og:site_name\" content=\"Gruppo Torelli Dottori\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T15:50:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/020-1-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1431\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/consorzio-shopping-center\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/consorzio-shopping-center\\\/\",\"name\":\"Consorzio Shopping Center | Gruppo Torelli Dottori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/consorzio-shopping-center\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/consorzio-shopping-center\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/020-1-scaled.webp\",\"datePublished\":\"2026-03-31T13:07:11+00:00\",\"dateModified\":\"2026-05-05T15:50:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/consorzio-shopping-center\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/consorzio-shopping-center\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/consorzio-shopping-center\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/020-1-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/020-1-scaled.webp\",\"width\":2560,\"height\":1431},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/project\\\/consorzio-shopping-center\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consorzio Shopping Center\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/\",\"name\":\"Gruppo Torelli Dottori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#organization\",\"name\":\"Gruppo Torelli Dottori\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"width\":500,\"height\":214,\"caption\":\"Gruppo Torelli Dottori\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consorzio Shopping Center | Gruppo Torelli Dottori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.torellidottori.com\/en\/project\/consorzio-shopping-center\/","og_locale":"en_US","og_type":"article","og_title":"Consorzio Shopping Center | Gruppo Torelli Dottori","og_description":"Location: S.S. Bocca Trabaria Sud n. 2, Urbino (PU) CONTACTS www.consorziocenter.com DOWNLOAD THE BROCHURE","og_url":"https:\/\/www.torellidottori.com\/en\/project\/consorzio-shopping-center\/","og_site_name":"Gruppo Torelli Dottori","article_modified_time":"2026-05-05T15:50:30+00:00","og_image":[{"width":2560,"height":1431,"url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/020-1-scaled.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.torellidottori.com\/en\/project\/consorzio-shopping-center\/","url":"https:\/\/www.torellidottori.com\/en\/project\/consorzio-shopping-center\/","name":"Consorzio Shopping Center | Gruppo Torelli Dottori","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.torellidottori.com\/en\/project\/consorzio-shopping-center\/#primaryimage"},"image":{"@id":"https:\/\/www.torellidottori.com\/en\/project\/consorzio-shopping-center\/#primaryimage"},"thumbnailUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/020-1-scaled.webp","datePublished":"2026-03-31T13:07:11+00:00","dateModified":"2026-05-05T15:50:30+00:00","breadcrumb":{"@id":"https:\/\/www.torellidottori.com\/en\/project\/consorzio-shopping-center\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.torellidottori.com\/en\/project\/consorzio-shopping-center\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.torellidottori.com\/en\/project\/consorzio-shopping-center\/#primaryimage","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/020-1-scaled.webp","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/020-1-scaled.webp","width":2560,"height":1431},{"@type":"BreadcrumbList","@id":"https:\/\/www.torellidottori.com\/en\/project\/consorzio-shopping-center\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.torellidottori.com\/en\/"},{"@type":"ListItem","position":2,"name":"Consorzio Shopping Center"}]},{"@type":"WebSite","@id":"https:\/\/www.torellidottori.com\/en\/#website","url":"https:\/\/www.torellidottori.com\/en\/","name":"Gruppo Torelli Dottori","description":"","publisher":{"@id":"https:\/\/www.torellidottori.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.torellidottori.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.torellidottori.com\/en\/#organization","name":"Gruppo Torelli Dottori","url":"https:\/\/www.torellidottori.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.torellidottori.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","width":500,"height":214,"caption":"Gruppo Torelli Dottori"},"image":{"@id":"https:\/\/www.torellidottori.com\/en\/#\/schema\/logo\/image\/"}}]}},"mfb_rest_fields":["title","blocksy_meta","yoast_head","yoast_head_json"],"_links":{"self":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/project\/2516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/media\/2515"}],"wp:attachment":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/media?parent=2516"}],"wp:term":[{"taxonomy":"project-category","embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/project-category?post=2516"},{"taxonomy":"project-tag","embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/project-tag?post=2516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}