{"id":1864,"date":"2015-04-07T15:43:11","date_gmt":"2015-04-07T13:43:11","guid":{"rendered":"https:\/\/www.torellidottori.com\/?p=1864"},"modified":"2026-05-08T11:15:13","modified_gmt":"2026-05-08T09:15:13","slug":"triulza-il-cantiere-piu-sostenibile-di-expo","status":"publish","type":"post","link":"https:\/\/www.torellidottori.com\/it\/triulza-il-cantiere-piu-sostenibile-di-expo\/","title":{"rendered":"Triulza il cantiere piu\u0300 sostenibile di EXPO"},"content":{"rendered":"\n<p>Il complesso della Cascina Triulza, oggetto del presente progetto, \u00e8 ubicato in via Cristina di Belgioioso 171, all\u2019interno del Sito Espositivo di Expo 2015.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2015_Triulza-il-cantiere-piu-sostenibile-di-EXPO.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of 2015_Triulza il cantiere piu\u0300 sostenibile di EXPO.\"><\/object><a class=\"wp-element-button\" id=\"wp-block-file--media-f75f2b79-bbbd-452d-933b-4da2e8b826f0\" href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2015_Triulza-il-cantiere-piu-sostenibile-di-EXPO.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Visualizza<\/a><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2015_Triulza-il-cantiere-piu-sostenibile-di-EXPO.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-f75f2b79-bbbd-452d-933b-4da2e8b826f0\">Scarica l&#8217;articolo<\/a><\/div>\n\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider stk-block stk-b8e5656\" data-block-id=\"b8e5656\"><style>.stk-b8e5656 hr.stk-block-divider__hr{background:var(--theme-palette-color-5, #e1e8ed) !important;height:2px !important;width:100% !important;}.stk-b8e5656 {padding-top:var(--stk--preset--spacing--60, 2.25rem) !important;padding-bottom:var(--stk--preset--spacing--60, 2.25rem) !important;}<\/style><hr class=\"stk-block-divider__hr\"\/><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-ec8efb1\" id=\"scopri-il-progetto-realizzato\" data-block-id=\"ec8efb1\"><h4 class=\"stk-block-heading__text\">Scopri il progetto realizzato<\/h4><\/div>\n\n\n\n<div class=\"wp-block-query is-layout-flow wp-block-query-is-layout-flow\"><ul class=\"wp-block-post-template is-layout-flow wp-block-post-template-is-layout-flow\"><li class=\"wp-block-post post-2348 project type-project status-publish has-post-thumbnail hentry project-category-renovation-works\">\n\n<div class=\"wp-block-columns are-vertically-aligned-center has-palette-color-8-background-color has-background is-layout-flex wp-container-core-columns-is-layout-85958d59 wp-block-columns-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--40);padding-right:var(--wp--preset--spacing--40);padding-bottom:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--40)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.torellidottori.com\/en\/project\/palazzo-gradari\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"388\" src=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/03\/13vu1tp0_opt.webp\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Palazzo Gradari\" style=\"object-fit:cover;\" \/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\"><h4 class=\"wp-block-post-title\"><a href=\"https:\/\/www.torellidottori.com\/en\/project\/palazzo-gradari\/\" target=\"_self\" >Palazzo Gradari<\/a><\/h4><\/div>\n<\/div>\n\n<\/li><\/ul><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il complesso della Cascina Triulza, oggetto del presente progetto, \u00e8 ubicato in via Cristina di Belgioioso 171, all\u2019interno del Sito Espositivo di Expo 2015. Scopri il progetto realizzato<\/p>\n","protected":false},"author":1,"featured_media":1866,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-1864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"blocksy_meta":[],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Triulza il cantiere piu\u0300 sostenibile di EXPO | Gruppo Torelli Dottori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.torellidottori.com\/en\/triulza-il-cantiere-piu-sostenibile-di-expo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Triulza il cantiere piu\u0300 sostenibile di EXPO | Gruppo Torelli Dottori\" \/>\n<meta property=\"og:description\" content=\"Il complesso della Cascina Triulza, oggetto del presente progetto, \u00e8 ubicato in via Cristina di Belgioioso 171, all\u2019interno del Sito Espositivo di Expo 2015. Scopri il progetto realizzato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.torellidottori.com\/it\/triulza-il-cantiere-piu-sostenibile-di-expo\/\" \/>\n<meta property=\"og:site_name\" content=\"Gruppo Torelli Dottori\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-07T13:43:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T09:15:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-154238.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"945\" \/>\n\t<meta property=\"og:image:height\" content=\"703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin_fliplab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_fliplab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/triulza-il-cantiere-piu-sostenibile-di-expo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/triulza-il-cantiere-piu-sostenibile-di-expo\\\/\"},\"author\":{\"name\":\"admin_fliplab\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#\\\/schema\\\/person\\\/2f1f4289eb9b223ef8a647f8ebd6ebb4\"},\"headline\":\"Triulza il cantiere piu\u0300 sostenibile di EXPO\",\"datePublished\":\"2015-04-07T13:43:11+00:00\",\"dateModified\":\"2026-05-08T09:15:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/triulza-il-cantiere-piu-sostenibile-di-expo\\\/\"},\"wordCount\":43,\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/triulza-il-cantiere-piu-sostenibile-di-expo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-154238.webp\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/triulza-il-cantiere-piu-sostenibile-di-expo\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/triulza-il-cantiere-piu-sostenibile-di-expo\\\/\",\"name\":\"Triulza il cantiere piu\u0300 sostenibile di EXPO | Gruppo Torelli Dottori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/triulza-il-cantiere-piu-sostenibile-di-expo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/triulza-il-cantiere-piu-sostenibile-di-expo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-154238.webp\",\"datePublished\":\"2015-04-07T13:43:11+00:00\",\"dateModified\":\"2026-05-08T09:15:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/triulza-il-cantiere-piu-sostenibile-di-expo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/triulza-il-cantiere-piu-sostenibile-di-expo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/triulza-il-cantiere-piu-sostenibile-di-expo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-154238.webp\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-154238.webp\",\"width\":945,\"height\":703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/triulza-il-cantiere-piu-sostenibile-di-expo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Triulza il cantiere piu\u0300 sostenibile di EXPO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/\",\"name\":\"Gruppo Torelli Dottori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#organization\",\"name\":\"Gruppo Torelli Dottori\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"width\":500,\"height\":214,\"caption\":\"Gruppo Torelli Dottori\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#\\\/schema\\\/person\\\/2f1f4289eb9b223ef8a647f8ebd6ebb4\",\"name\":\"admin_fliplab\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g\",\"caption\":\"admin_fliplab\"},\"sameAs\":[\"https:\\\/\\\/www.torellidottori.com\"],\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/author\\\/admin_fliplab\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Triulza il cantiere piu\u0300 sostenibile di EXPO | Gruppo Torelli Dottori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.torellidottori.com\/en\/triulza-il-cantiere-piu-sostenibile-di-expo\/","og_locale":"en_US","og_type":"article","og_title":"Triulza il cantiere piu\u0300 sostenibile di EXPO | Gruppo Torelli Dottori","og_description":"Il complesso della Cascina Triulza, oggetto del presente progetto, \u00e8 ubicato in via Cristina di Belgioioso 171, all\u2019interno del Sito Espositivo di Expo 2015. Scopri il progetto realizzato","og_url":"https:\/\/www.torellidottori.com\/it\/triulza-il-cantiere-piu-sostenibile-di-expo\/","og_site_name":"Gruppo Torelli Dottori","article_published_time":"2015-04-07T13:43:11+00:00","article_modified_time":"2026-05-08T09:15:13+00:00","og_image":[{"width":945,"height":703,"url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-154238.webp","type":"image\/png"}],"author":"admin_fliplab","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin_fliplab","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.torellidottori.com\/it\/triulza-il-cantiere-piu-sostenibile-di-expo\/#article","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/it\/triulza-il-cantiere-piu-sostenibile-di-expo\/"},"author":{"name":"admin_fliplab","@id":"https:\/\/www.torellidottori.com\/en\/#\/schema\/person\/2f1f4289eb9b223ef8a647f8ebd6ebb4"},"headline":"Triulza il cantiere piu\u0300 sostenibile di EXPO","datePublished":"2015-04-07T13:43:11+00:00","dateModified":"2026-05-08T09:15:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.torellidottori.com\/it\/triulza-il-cantiere-piu-sostenibile-di-expo\/"},"wordCount":43,"publisher":{"@id":"https:\/\/www.torellidottori.com\/en\/#organization"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/triulza-il-cantiere-piu-sostenibile-di-expo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-154238.webp","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.torellidottori.com\/it\/triulza-il-cantiere-piu-sostenibile-di-expo\/","url":"https:\/\/www.torellidottori.com\/it\/triulza-il-cantiere-piu-sostenibile-di-expo\/","name":"Triulza il cantiere piu\u0300 sostenibile di EXPO | Gruppo Torelli Dottori","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.torellidottori.com\/it\/triulza-il-cantiere-piu-sostenibile-di-expo\/#primaryimage"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/triulza-il-cantiere-piu-sostenibile-di-expo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-154238.webp","datePublished":"2015-04-07T13:43:11+00:00","dateModified":"2026-05-08T09:15:13+00:00","breadcrumb":{"@id":"https:\/\/www.torellidottori.com\/it\/triulza-il-cantiere-piu-sostenibile-di-expo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.torellidottori.com\/it\/triulza-il-cantiere-piu-sostenibile-di-expo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.torellidottori.com\/it\/triulza-il-cantiere-piu-sostenibile-di-expo\/#primaryimage","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-154238.webp","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-154238.webp","width":945,"height":703},{"@type":"BreadcrumbList","@id":"https:\/\/www.torellidottori.com\/it\/triulza-il-cantiere-piu-sostenibile-di-expo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.torellidottori.com\/en\/"},{"@type":"ListItem","position":2,"name":"Triulza il cantiere piu\u0300 sostenibile di EXPO"}]},{"@type":"WebSite","@id":"https:\/\/www.torellidottori.com\/en\/#website","url":"https:\/\/www.torellidottori.com\/en\/","name":"Gruppo Torelli Dottori","description":"","publisher":{"@id":"https:\/\/www.torellidottori.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.torellidottori.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.torellidottori.com\/en\/#organization","name":"Gruppo Torelli Dottori","url":"https:\/\/www.torellidottori.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.torellidottori.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","width":500,"height":214,"caption":"Gruppo Torelli Dottori"},"image":{"@id":"https:\/\/www.torellidottori.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.torellidottori.com\/en\/#\/schema\/person\/2f1f4289eb9b223ef8a647f8ebd6ebb4","name":"admin_fliplab","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g","caption":"admin_fliplab"},"sameAs":["https:\/\/www.torellidottori.com"],"url":"https:\/\/www.torellidottori.com\/en\/author\/admin_fliplab\/"}]}},"mfb_rest_fields":["title","blocksy_meta","yoast_head","yoast_head_json"],"_links":{"self":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/posts\/1864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/comments?post=1864"}],"version-history":[{"count":0,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/posts\/1864\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/media\/1866"}],"wp:attachment":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/media?parent=1864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/categories?post=1864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/tags?post=1864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}