{"id":1822,"date":"2018-03-07T12:34:50","date_gmt":"2018-03-07T11:34:50","guid":{"rendered":"https:\/\/www.torellidottori.com\/?p=1822"},"modified":"2026-05-08T11:15:12","modified_gmt":"2026-05-08T09:15:12","slug":"scuola-primaria-casenuove-comune-di-osimo","status":"publish","type":"post","link":"https:\/\/www.torellidottori.com\/it\/scuola-primaria-casenuove-comune-di-osimo\/","title":{"rendered":"Scuola Primaria Casenuove Comune di Osimo"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2018.03_Scuola-Primaria-Casenuove-Comune-di-Osimo.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of 2018.03_Scuola Primaria Casenuove Comune di Osimo.\"><\/object><a class=\"wp-element-button\" id=\"wp-block-file--media-7e45e873-29e5-4cfc-9f24-2abcc4c705a2\" href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2018.03_Scuola-Primaria-Casenuove-Comune-di-Osimo.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Visualizza<\/a><a href=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/2018.03_Scuola-Primaria-Casenuove-Comune-di-Osimo.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-7e45e873-29e5-4cfc-9f24-2abcc4c705a2\">Scarica l&#8217;articolo<\/a><\/div>\n\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider stk-block stk-b8e5656\" data-block-id=\"b8e5656\"><style>.stk-b8e5656 hr.stk-block-divider__hr{background:var(--theme-palette-color-5, #e1e8ed) !important;height:2px !important;width:100% !important;}.stk-b8e5656 {padding-top:var(--stk--preset--spacing--60, 2.25rem) !important;padding-bottom:var(--stk--preset--spacing--60, 2.25rem) !important;}<\/style><hr class=\"stk-block-divider__hr\"\/><\/div>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1827,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-1822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"blocksy_meta":[],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scuola Primaria Casenuove Comune di Osimo | Gruppo Torelli Dottori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.torellidottori.com\/en\/scuola-primaria-casenuove-comune-di-osimo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scuola Primaria Casenuove Comune di Osimo | Gruppo Torelli Dottori\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.torellidottori.com\/it\/scuola-primaria-casenuove-comune-di-osimo\/\" \/>\n<meta property=\"og:site_name\" content=\"Gruppo Torelli Dottori\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-07T11:34:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T09:15:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-123434.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"505\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin_fliplab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_fliplab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/scuola-primaria-casenuove-comune-di-osimo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/scuola-primaria-casenuove-comune-di-osimo\\\/\"},\"author\":{\"name\":\"admin_fliplab\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#\\\/schema\\\/person\\\/2f1f4289eb9b223ef8a647f8ebd6ebb4\"},\"headline\":\"Scuola Primaria Casenuove Comune di Osimo\",\"datePublished\":\"2018-03-07T11:34:50+00:00\",\"dateModified\":\"2026-05-08T09:15:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/scuola-primaria-casenuove-comune-di-osimo\\\/\"},\"wordCount\":19,\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/scuola-primaria-casenuove-comune-di-osimo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-123434.webp\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/scuola-primaria-casenuove-comune-di-osimo\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/scuola-primaria-casenuove-comune-di-osimo\\\/\",\"name\":\"Scuola Primaria Casenuove Comune di Osimo | Gruppo Torelli Dottori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/scuola-primaria-casenuove-comune-di-osimo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/scuola-primaria-casenuove-comune-di-osimo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-123434.webp\",\"datePublished\":\"2018-03-07T11:34:50+00:00\",\"dateModified\":\"2026-05-08T09:15:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/scuola-primaria-casenuove-comune-di-osimo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/scuola-primaria-casenuove-comune-di-osimo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/scuola-primaria-casenuove-comune-di-osimo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-123434.webp\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Immagine-2026-04-07-123434.webp\",\"width\":760,\"height\":505},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/it\\\/scuola-primaria-casenuove-comune-di-osimo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scuola Primaria Casenuove Comune di Osimo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/\",\"name\":\"Gruppo Torelli Dottori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#organization\",\"name\":\"Gruppo Torelli Dottori\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"contentUrl\":\"https:\\\/\\\/www.torellidottori.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LOGO-TORELLI-DOTTORI_500_def.png\",\"width\":500,\"height\":214,\"caption\":\"Gruppo Torelli Dottori\"},\"image\":{\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/#\\\/schema\\\/person\\\/2f1f4289eb9b223ef8a647f8ebd6ebb4\",\"name\":\"admin_fliplab\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g\",\"caption\":\"admin_fliplab\"},\"sameAs\":[\"https:\\\/\\\/www.torellidottori.com\"],\"url\":\"https:\\\/\\\/www.torellidottori.com\\\/en\\\/author\\\/admin_fliplab\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scuola Primaria Casenuove Comune di Osimo | Gruppo Torelli Dottori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.torellidottori.com\/en\/scuola-primaria-casenuove-comune-di-osimo\/","og_locale":"en_US","og_type":"article","og_title":"Scuola Primaria Casenuove Comune di Osimo | Gruppo Torelli Dottori","og_url":"https:\/\/www.torellidottori.com\/it\/scuola-primaria-casenuove-comune-di-osimo\/","og_site_name":"Gruppo Torelli Dottori","article_published_time":"2018-03-07T11:34:50+00:00","article_modified_time":"2026-05-08T09:15:12+00:00","og_image":[{"width":760,"height":505,"url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-123434.webp","type":"image\/png"}],"author":"admin_fliplab","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin_fliplab","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.torellidottori.com\/it\/scuola-primaria-casenuove-comune-di-osimo\/#article","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/it\/scuola-primaria-casenuove-comune-di-osimo\/"},"author":{"name":"admin_fliplab","@id":"https:\/\/www.torellidottori.com\/en\/#\/schema\/person\/2f1f4289eb9b223ef8a647f8ebd6ebb4"},"headline":"Scuola Primaria Casenuove Comune di Osimo","datePublished":"2018-03-07T11:34:50+00:00","dateModified":"2026-05-08T09:15:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.torellidottori.com\/it\/scuola-primaria-casenuove-comune-di-osimo\/"},"wordCount":19,"publisher":{"@id":"https:\/\/www.torellidottori.com\/en\/#organization"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/scuola-primaria-casenuove-comune-di-osimo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-123434.webp","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.torellidottori.com\/it\/scuola-primaria-casenuove-comune-di-osimo\/","url":"https:\/\/www.torellidottori.com\/it\/scuola-primaria-casenuove-comune-di-osimo\/","name":"Scuola Primaria Casenuove Comune di Osimo | Gruppo Torelli Dottori","isPartOf":{"@id":"https:\/\/www.torellidottori.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.torellidottori.com\/it\/scuola-primaria-casenuove-comune-di-osimo\/#primaryimage"},"image":{"@id":"https:\/\/www.torellidottori.com\/it\/scuola-primaria-casenuove-comune-di-osimo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-123434.webp","datePublished":"2018-03-07T11:34:50+00:00","dateModified":"2026-05-08T09:15:12+00:00","breadcrumb":{"@id":"https:\/\/www.torellidottori.com\/it\/scuola-primaria-casenuove-comune-di-osimo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.torellidottori.com\/it\/scuola-primaria-casenuove-comune-di-osimo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.torellidottori.com\/it\/scuola-primaria-casenuove-comune-di-osimo\/#primaryimage","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-123434.webp","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/Immagine-2026-04-07-123434.webp","width":760,"height":505},{"@type":"BreadcrumbList","@id":"https:\/\/www.torellidottori.com\/it\/scuola-primaria-casenuove-comune-di-osimo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.torellidottori.com\/en\/"},{"@type":"ListItem","position":2,"name":"Scuola Primaria Casenuove Comune di Osimo"}]},{"@type":"WebSite","@id":"https:\/\/www.torellidottori.com\/en\/#website","url":"https:\/\/www.torellidottori.com\/en\/","name":"Gruppo Torelli Dottori","description":"","publisher":{"@id":"https:\/\/www.torellidottori.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.torellidottori.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.torellidottori.com\/en\/#organization","name":"Gruppo Torelli Dottori","url":"https:\/\/www.torellidottori.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.torellidottori.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","contentUrl":"https:\/\/www.torellidottori.com\/wp-content\/uploads\/2026\/04\/LOGO-TORELLI-DOTTORI_500_def.png","width":500,"height":214,"caption":"Gruppo Torelli Dottori"},"image":{"@id":"https:\/\/www.torellidottori.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.torellidottori.com\/en\/#\/schema\/person\/2f1f4289eb9b223ef8a647f8ebd6ebb4","name":"admin_fliplab","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ee7f43f04b3a4a0c47d157ae957b3ba3a7cd5cdc1db6e4da3ff91cbc4a2c2c44?s=96&d=mm&r=g","caption":"admin_fliplab"},"sameAs":["https:\/\/www.torellidottori.com"],"url":"https:\/\/www.torellidottori.com\/en\/author\/admin_fliplab\/"}]}},"mfb_rest_fields":["title","blocksy_meta","yoast_head","yoast_head_json"],"_links":{"self":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/posts\/1822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/comments?post=1822"}],"version-history":[{"count":0,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/posts\/1822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/media\/1827"}],"wp:attachment":[{"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/media?parent=1822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/categories?post=1822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.torellidottori.com\/en\/wp-json\/wp\/v2\/tags?post=1822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}